{"id":121,"date":"2006-12-19T05:12:00","date_gmt":"2006-12-19T08:12:00","guid":{"rendered":"http:\/\/www.schwartzman.org.br\/sitesimon\/?p=121"},"modified":"2008-08-03T14:27:07","modified_gmt":"2008-08-03T17:27:07","slug":"comenarios-anonimos-tema-da-raca","status":"publish","type":"post","link":"https:\/\/www.schwartzman.org.br\/sitesimon\/comenarios-anonimos-tema-da-raca\/","title":{"rendered":"Coment\u00e1rios an\u00f4nimos, tema da ra\u00e7a"},"content":{"rendered":"<p>Recebi um longo coment\u00e1rio sobre o livro de Ali Kamel, <span style=\"font-style: italic;\">N\u00e3o somos Racistas<\/span>,  que tive que rejeitar, porque n\u00e3o tinha identifica\u00e7\u00e3o do autor. Estou respondendo por aqui porque n\u00e3o tenho como responder ao autor pessoalmente. O sistema de coment\u00e1rios do blog tem um lugar para a identifica\u00e7\u00e3o das pessoas, e tenho adotado a norma de s\u00f3 publicar coment\u00e1rios e textos assinados, por raz\u00f5es \u00f3bvias.<\/p>\n<p>Meses atr\u00e1s, coloquei uma nota dizendo que estava encerrando a discuss\u00e3o do tema da ra\u00e7a neste blog, n\u00e3o porque o tema havia perdido sua import\u00e2ncia social e pol\u00edtica, mas porque a discuss\u00e3o me parecia que estava andando em c\u00edrculos, com os argumentos se repetindo.  N\u00e3o tenho mantido esta regra \u00e0 risca, mas queria lembrar que existem v\u00e1rias listas de discuss\u00e3o espec\u00edfica sobre o tema, antre as quais norace-l[at]ensp.fiocruz.br, e sugiro aos que queiram participar dela que solicitem sua inscri\u00e7\u00e3o a Marcos Maio, maiomarcos[at]uol.com.br.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Recebi um longo coment\u00e1rio sobre o livro de Ali Kamel, N\u00e3o somos Racistas, que tive que rejeitar, porque n\u00e3o tinha identifica\u00e7\u00e3o do autor. Estou respondendo por aqui porque n\u00e3o tenho como responder ao autor pessoalmente. O sistema de coment\u00e1rios do blog tem um lugar para a identifica\u00e7\u00e3o das pessoas, e tenho adotado a norma de &hellip; <a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/comenarios-anonimos-tema-da-raca\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Coment\u00e1rios an\u00f4nimos, tema da ra\u00e7a&#8221;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[14],"tags":[],"class_list":["post-121","post","type-post","status-publish","format-standard","hentry","category-politica-racial"],"_links":{"self":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/comments?post=121"}],"version-history":[{"count":2,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/121\/revisions"}],"predecessor-version":[{"id":433,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/121\/revisions\/433"}],"wp:attachment":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/media?parent=121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/categories?post=121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/tags?post=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}