{"id":1374,"date":"2009-08-10T15:14:37","date_gmt":"2009-08-10T18:14:37","guid":{"rendered":"http:\/\/www.schwartzman.org.br\/sitesimon\/?p=1374"},"modified":"2009-08-11T02:21:06","modified_gmt":"2009-08-11T05:21:06","slug":"esperancas-para-a-usphopes-for-usp","status":"publish","type":"post","link":"https:\/\/www.schwartzman.org.br\/sitesimon\/esperancas-para-a-usphopes-for-usp\/","title":{"rendered":"Esperan\u00e7a para a USP|Hopes for USP"},"content":{"rendered":"<p><script type='application\/json' class='__iawmlf-post-loop-links'>[{\"id\":713,\"href\":\"http:\\\/\\\/www.schwartzman.org.br\\\/simon\\\/usp_reit.pdf\",\"archived_href\":\"\",\"redirect_href\":\"\",\"checks\":[],\"broken\":false,\"last_checked\":null,\"process\":\"done\"},{\"id\":715,\"href\":\"http:\\\/\\\/www.schwartzman.org.br\\\/simon\\\/worldclass_pt.pdf\",\"archived_href\":\"\",\"redirect_href\":\"\",\"checks\":[],\"broken\":false,\"last_checked\":null,\"process\":\"done\"},{\"id\":714,\"href\":\"http:\\\/\\\/www.schwartzman.org.br\\\/simon\\\/worldclasss.pdf\",\"archived_href\":\"\",\"redirect_href\":\"\",\"checks\":[],\"broken\":false,\"last_checked\":null,\"process\":\"done\"}]<\/script>A pr\u00f3xima elei\u00e7\u00e3o para reitor da Universidade de S\u00e3o Paulo est\u00e1 permitindo iniciar uma discuss\u00e3o interna muito necess\u00e1ria sobre como deve ser e como deve evoluir a mais importante universidade do pa\u00eds, que tem passado por um per\u00edodo dif\u00edcil de conflagra\u00e7\u00f5es, burocratiza\u00e7\u00e3o e falta de rumo. Seis professores &#8211; Adalberto de Fazzio, Glauco Arbix, Hern\u00e1n Chaimovich, Jorge Kalil Filho, Marco Antonio Zago, Renato Janine Ribeiro , Vahan Agopyan &#8211;\u00a0 lan\u00e7aram um manifesto em que afirmam que a USP precisa urgentemente\u00a0 mudar, a partir da lideran\u00e7a de seus professores mais qualificados, que hoje muitas vezes se mant\u00eam\u00a0 isolados em seus departamentos e projetos, ante a rigidez burocr\u00e1tica e as dificuldades de gest\u00e3o da universidade, &#8220;acompanhadas muitas vezes de atitudes de rejei\u00e7\u00e3o \u00e0 lideran\u00e7a destes cientistas nas estruturas departamentais&#8221;.<\/p>\n<p>O manifesto diz ainda que\u00a0&#8220;a exist\u00eancia de grupos ou cursos de reduzida relev\u00e2ncia acad\u00eamica, quer no ensino ou na pesquisa, \u00e9 sim responsabilidade da reitoria e das diretorias, e exige formas criativas de interven\u00e7\u00e3o por parte das autoridades acad\u00eamicas, visando a garantir que uns mantenham ou ampliem a sua lideran\u00e7a e outros passem a estar \u00e0 altura da miss\u00e3o da USP&#8221;. Esta \u00e9 uma proposta realmente revolucion\u00e1ria no meio universit\u00e1rio brasileiro, em que predomina uma falsa democracia que trata a todos os departamentos e cursos das institui\u00e7\u00f5es como iguais, independentemente da contribui\u00e7\u00e3o que estejam dando em termos dos objetivos cient\u00edficos e educacionais das institui\u00e7\u00f5es. O manifesto \u00e9 muito mais do que isto, e <a href=\"http:\/\/www.schwartzman.org.br\/simon\/usp_reit.pdf\" target=\"_blank\">o texto integral est\u00e1 disponivel aqui. <\/a><\/p>\n<p>Em 2006 escrevi um artigo,\u00a0<span lang=\"pt-br\"> &#8220;<a href=\"http:\/\/www.schwartzman.org.br\/simon\/worldclass_pt.pdf\" target=\"_blank\">A universidade primeira do Brasil: entre intelligentsia, padr\u00e3o internacional e inclus\u00e3o social.<\/a>&#8220;<\/span> <span lang=\"en-us\">&#8220;<a href=\"http:\/\/www.schwartzman.org.br\/simon\/worldclasss.pdf\" target=\"_blank\">Brazil\u2019s leading university: between intelligentsia, world standards and social inclusion&#8221;<\/a><\/span>,\u00a0 em que dizia que a USP, pelos recursos humanos e financeiros que tem, teria todas as condi\u00e7oes de se transformar em uma universidade de padr\u00e3o efetivamente internacional, pela qualidade de suas pesquisas e dos profissionais que forma, pela contribui\u00e7\u00e3o que pode dar para a sociedade e para a economia, e pela janela que pode significar para os avan\u00e7os da ci\u00eancia e da tecnologia em todo o mundo.\u00a0 O que parecia faltar era, aparentemente, um consenso interno a respeito da import\u00e2ncia de assumir este papel e das transforma\u00e7\u00f5es institucionais necess\u00e1rias para ir adiante. Acredito que este manifesto reflete a mesma preocupa\u00e7\u00e3o, embora colocada em outros termos, e espero que possa ter a repercuss\u00e3o e os efeitos que a Universidade de S\u00e3o Paulo merece.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>A pr\u00f3xima elei\u00e7\u00e3o para reitor da Universidade de S\u00e3o Paulo est\u00e1 permitindo iniciar uma discuss\u00e3o interna muito necess\u00e1ria sobre como deve ser e como deve evoluir a mais importante universidade do pa\u00eds, que tem passado por um per\u00edodo dif\u00edcil de conflagra\u00e7\u00f5es, burocratiza\u00e7\u00e3o e falta de rumo. Seis professores &#8211; Adalberto de Fazzio, Glauco Arbix, Hern\u00e1n &hellip; <a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/esperancas-para-a-usphopes-for-usp\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Esperan\u00e7a para a USP|Hopes for USP&#8221;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[11],"tags":[],"class_list":["post-1374","post","type-post","status-publish","format-standard","hentry","category-educacao-superior"],"_links":{"self":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/1374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/comments?post=1374"}],"version-history":[{"count":3,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/1374\/revisions"}],"predecessor-version":[{"id":1384,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/1374\/revisions\/1384"}],"wp:attachment":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/media?parent=1374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/categories?post=1374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/tags?post=1374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}