{"id":150,"date":"2007-05-24T12:39:00","date_gmt":"2007-05-24T15:39:00","guid":{"rendered":"http:\/\/www.schwartzman.org.br\/sitesimon\/?p=150"},"modified":"2009-10-07T11:23:22","modified_gmt":"2009-10-07T14:23:22","slug":"maria-tereza-goudard-tavares-alfabetizacao-em-sao-goncalo","status":"publish","type":"post","link":"https:\/\/www.schwartzman.org.br\/sitesimon\/maria-tereza-goudard-tavares-alfabetizacao-em-sao-goncalo\/","title":{"rendered":"Maria Tereza Goudard Tavares: Alfabetiza\u00e7\u00e3o em S\u00e3o Gon\u00e7alo"},"content":{"rendered":"<p><span style=\"font-style: italic;\">Recebi da Professora Maria Tereza Goudard Tavares a seguinte nota, a respeito do que publiquei antes com o t\u00edtulo de &#8220;<a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/?p=148&amp;lang=en-us\" target=\"_blank\">Os burros de S\u00e3o Gon\u00e7alo<\/a>&#8220;: <\/span><\/p>\n<p>Caro Senhor Simon,<\/p>\n<p>Agrade\u00e7o o espa\u00e7o de discuss\u00e3o, saudando o seu compromisso com o di\u00e1logo democr\u00e1tico. Em linhas gerais foram estas as minhas palavras aos jornalistas que me entrevistaram por telefone, com rela\u00e7\u00e3o \u00e0 ado\u00e7\u00e3o do programa Alfa \u2013 Beto:<\/p>\n<p>I \u2013 Quanto ao uso do programa e a sua implementa\u00e7\u00e3o junto \u00e0 rede a partir de 2007, achamos ser necess\u00e1rio que se realize um profundo diagn\u00f3stico das condi\u00e7\u00f5es estruturais e materiais da rede, destacando \u00e0s condi\u00e7\u00f5es de trabalho das professoras alfabetizadoras e das escolas em que as mesmas trabalham;<\/p>\n<p>II-  A quest\u00e3o da prioridade no uso da verba p\u00fablica municipal nas compra dos kit\u00b4s do programa \u2013 \u00c9 bom ressaltar que o  Programa Nacional do Livro Did\u00e1tico (PNLD) vem sendo desenvolvido com sucesso nos munic\u00edpios do estado do Rio de Janeiro, \u00e9 que em S\u00e3o Gon\u00e7alo, os livros tem chegado \u00e0s escolas, em especial, \u00e0s classes de alfabetiza\u00e7\u00e3o, sem \u00f4nus para SME \/ Prefeitura de S\u00e3o Gon\u00e7alo;<\/p>\n<p>III \u2013 A forma pela qual a SME \/ SG definiu a ado\u00e7\u00e3o e a implementa\u00e7\u00e3o do Programa Alfa \u2013 Beto. Defendemos que a professora deve ter o direito de participar da escolha de seu m\u00e9todo de trabalho, e que a ado\u00e7\u00e3o de um m\u00e9todo \u00fanico, seja este filiado a qualquer matriz epistemol\u00f3gica, n\u00e3o d\u00e1 conta da multiplicidade dos saberes e fazeres no processo de alfabetiza\u00e7\u00e3o.<\/p>\n<p>Nesse sentido, achamos que a Secretaria  Municipal de Educa\u00e7\u00e3o, ciente de seu papel pol\u00edtico e pedag\u00f3gico deve avaliar com muita acuidade e serenidade a ado\u00e7\u00e3o do Programa Alfa \u2013 Beto, bem como a sua implementa\u00e7\u00e3o generalizada na rede. Ressaltamos que \u00e0 ado\u00e7\u00e3o pouco democr\u00e1tica e verticalizada do m\u00e9todo \u00fanico, fere inclusive, o preceito legal garantido pela Lei de Diretrizes e Bases da Educa\u00e7\u00e3o Nacional (LDB\/96), que garante ao docente a liberdade de ensinar.<\/p>\n<p>Atenciosamente,<br \/>\nProf. Dr\u00aa. Maria Tereza Goudard Tavares (UERJ\/FFP)<br \/>\nConselheira Municipal de Educa\u00e7\u00e3o de S\u00e3o Gon\u00e7alo<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Recebi da Professora Maria Tereza Goudard Tavares a seguinte nota, a respeito do que publiquei antes com o t\u00edtulo de &#8220;Os burros de S\u00e3o Gon\u00e7alo&#8220;: Caro Senhor Simon, Agrade\u00e7o o espa\u00e7o de discuss\u00e3o, saudando o seu compromisso com o di\u00e1logo democr\u00e1tico. Em linhas gerais foram estas as minhas palavras aos jornalistas que me entrevistaram por &hellip; <a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/maria-tereza-goudard-tavares-alfabetizacao-em-sao-goncalo\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Maria Tereza Goudard Tavares: Alfabetiza\u00e7\u00e3o em S\u00e3o Gon\u00e7alo&#8221;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[7],"tags":[],"class_list":["post-150","post","type-post","status-publish","format-standard","hentry","category-educacao-basica"],"_links":{"self":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/comments?post=150"}],"version-history":[{"count":2,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/150\/revisions"}],"predecessor-version":[{"id":1466,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/150\/revisions\/1466"}],"wp:attachment":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/media?parent=150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/categories?post=150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/tags?post=150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}