{"id":155,"date":"2007-06-11T10:36:00","date_gmt":"2007-06-11T13:36:00","guid":{"rendered":"http:\/\/www.schwartzman.org.br\/sitesimon\/?p=155"},"modified":"2008-08-03T12:52:52","modified_gmt":"2008-08-03T15:52:52","slug":"o-melhor-sistema-de-saude-publica-do-mundo-medicos-na-cadeia","status":"publish","type":"post","link":"https:\/\/www.schwartzman.org.br\/sitesimon\/o-melhor-sistema-de-saude-publica-do-mundo-medicos-na-cadeia\/","title":{"rendered":"O melhor sistema de sa\u00fade p\u00fablica do mundo: m\u00e9dicos na cadeia"},"content":{"rendered":"<p><span style=\"font-style: italic;\">O Globo<\/span> de hoje, 11\/06\/2007, noticia que a Dra. Yolanda Cyranka, chefe de equipe do Hospital Miguel Couto no Rio de Janeiro, foi presa por desrespeitar ordem do Tribunal de Justi\u00e7a do Rio para transferir um paciente para um hospital particular, porque a UTI do hospital p\u00fablico n\u00e3o tinha vaga.<\/p>\n<p>No dia 15 de maio passado, o secret\u00e1rio estadual de Sa\u00fade e o gerente estadual de Ger\u00eancia Farmac\u00eautica do Esp\u00edrito Santo foram presos pela Pol\u00edcia Federal por descumprirem uma determina\u00e7\u00e3o de um juiz federal de Colatina, no interior do Estado. Segundo a Justi\u00e7a, a Secretaria da Sa\u00fade deveria ter fornecido o medicamento Avastin \u00e0 fam\u00edlia de uma crian\u00e7a de cinco anos, que est\u00e1 com tumor cerebral e se encontra em estado grave. Conforme noticiou o jornal <span style=\"font-style: italic;\">A Tarde<\/span>, uma dose do rem\u00e9dio custa mais de R$ 5 mil. \u201cO secret\u00e1rio alega que a encomenda j\u00e1 havia sido feita, mas o laborat\u00f3rio n\u00e3o p\u00f4de cumprir o prazo determinado e a justi\u00e7a j\u00e1 havia sido informada.\u201d<\/p>\n<p>\u00c9 muito comum ouvir a afirma\u00e7\u00e3o de que nosso Sistema Unificado de Sa\u00fade, o SUS, implantado a partir da Constitui\u00e7\u00e3o de 1988, \u00e9 o melhor do mundo (veja por exemplo o artigo de Juliano Carvalho Lima, Mestre em Sa\u00fade P\u00fablica pelo Instituto Oswaldo Cruz,  ou o documento da CUT no mesmo sentido).<\/p>\n<p>A qualidade do sistema consistiria no princ\u00edpio de que o atendimento \u00e0 sa\u00fade \u00e9 direito de todos e dever do Estado, al\u00e9m de sua gest\u00e3o comunit\u00e1ria, de forma descentralizada e aut\u00f4noma. Quando um doente precisa de um tratamento, e as autoridades da \u00e1rea de sa\u00fade n\u00e3o o atendem, ent\u00e3o a justi\u00e7a interv\u00e9m, ordenando que o atendimento seja feito, e mandando prender os que n\u00e3o cumprem a ordem judicial.<\/p>\n<p>Falta s\u00f3 um pequeno detalhe, que \u00e9 o dinheiro para criar toda a infra-estrutura de atendimento, comprar todos os rem\u00e9dios e fazer todos os exames que sejam necess\u00e1rios. Na \u00e1rea da sa\u00fade, mais do que em outras, os custos dos equipamentos, rem\u00e9dios e da aten\u00e7\u00e3o profissional s\u00e3o crescentes, e, como o valor da vida \u00e9 incomensur\u00e1vel, sempre se pode gastar mais para atender a quem necessita; mas os recursos, por mais que cres\u00e7am,  ser\u00e3o sempre  insuficientes. Todos os servi\u00e7os de sa\u00fade do mundo, mesmo nos pa\u00edses mais ricos, t\u00eam que enfrentar este problema, atrav\u00e9s de prioridades, participa\u00e7\u00e3o dos pacientes nos custos dos servi\u00e7os (n\u00e3o s\u00f3 para arrecadar algum dinheiro, mas para desestimular a demanda por atendimentos menos priorit\u00e1rios) e o estabelecimento de padr\u00f5es autorizados de tratamento, entre outras medidas.<\/p>\n<p>O ativismo judici\u00e1rio no sistema de sa\u00fade, com juizes obrigando as autoridades m\u00e9dicas a dar prioridade aos casos que chegam \u00e0s suas m\u00e3os, s\u00f3 agrava as enormes dificuldades que o setor enfrenta, tendo que escolher, todos os dias, como usar melhor os parcos recursos de que disp\u00f5e.<\/p>\n<p>Est\u00e1 na hora de dizer que o Sistema Unificado de Sa\u00fade n\u00e3o s\u00f3 n\u00e3o \u00e9 o melhor do mundo, mas, muito pelo contr\u00e1rio, tem v\u00edcios de concep\u00e7\u00e3o e organiza\u00e7\u00e3o insan\u00e1veis, que t\u00eam como resultado o p\u00e9ssimo atendimento \u00e0 popula\u00e7\u00e3o que depende dele, e que precisam ser profundamente revistos.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>O Globo de hoje, 11\/06\/2007, noticia que a Dra. Yolanda Cyranka, chefe de equipe do Hospital Miguel Couto no Rio de Janeiro, foi presa por desrespeitar ordem do Tribunal de Justi\u00e7a do Rio para transferir um paciente para um hospital particular, porque a UTI do hospital p\u00fablico n\u00e3o tinha vaga. No dia 15 de maio &hellip; <a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/o-melhor-sistema-de-saude-publica-do-mundo-medicos-na-cadeia\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;O melhor sistema de sa\u00fade p\u00fablica do mundo: m\u00e9dicos na cadeia&#8221;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[23],"tags":[],"class_list":["post-155","post","type-post","status-publish","format-standard","hentry","category-saude"],"_links":{"self":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/comments?post=155"}],"version-history":[{"count":2,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/155\/revisions"}],"predecessor-version":[{"id":350,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/155\/revisions\/350"}],"wp:attachment":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/media?parent=155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/categories?post=155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/tags?post=155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}