{"id":173,"date":"2007-09-25T05:57:00","date_gmt":"2007-09-25T08:57:00","guid":{"rendered":"http:\/\/www.schwartzman.org.br\/sitesimon\/?p=173"},"modified":"2022-12-15T20:08:39","modified_gmt":"2022-12-15T23:08:39","slug":"por-uma-nova-politica-de-educacao-superior","status":"publish","type":"post","link":"https:\/\/www.schwartzman.org.br\/sitesimon\/por-uma-nova-politica-de-educacao-superior\/","title":{"rendered":"Por uma nova pol\u00edtica de educa\u00e7\u00e3o superior"},"content":{"rendered":"<p><a onblur=\"try {parent.deselectBloggerImageGracefully();} catch(e) {}\" href=\"http:\/\/bp3.blogger.com\/_QiS7NmwxcOc\/RvjhtL2RsNI\/AAAAAAAAADQ\/8fVNUDHLIUg\/s1600-h\/rendasup.jpg\"><\/a><\/p>\n<p>Convidado pelo PSDB, participei no dia 24 de setembro de um semin\u00e1rio sobre educa\u00e7\u00e3o, aonde fiz uma apresenta\u00e7\u00e3o que est\u00e1 <a href=\"http:\/\/www.schwartzman.org.br\/simon\/poledsup.pdf\">dispon\u00edvel aqui,<\/a>  e que tem a vantagem de ter somente seis p\u00e1ginas.<\/p>\n<p>Creio que houve bastante consenso entre os participantes da mesa &#8211; C\u00e9sar S\u00e1 Barreto, Carlos Brito Cruz e Ab\u00edlio Baeta Neves &#8211; exceto em um ponto, que \u00e9  o da cobran\u00e7a de anuidades no ensino superior p\u00fablico,  como j\u00e1 acontece em praticamente  todo o mundo, incluindo o M\u00e9xico, a Argentina, o Chile, a Fran\u00e7a e a China. Brito Cruz discordou, e, no encerramento, o governador Jos\u00e9 Serra tamb\u00e9m disse que era contra.<\/p>\n<p>Um forte argmento contra esta cobran\u00e7a \u00e9 que ela n\u00e3o traria  muitos recursos, seria complicada de implantar, e criaria um enorme problema pol\u00edtico. Por outro lado, os recursos podem ser significativos, e as universidades poderiam utiliz\u00e1-los, por exemplo, em programas de apoio a estudantes efetivamente carentes,  contribuindo assim para reduzir a dupla iniq\u00fcidade da educa\u00e7\u00e3o superior p\u00fablica brasileira &#8211; o subs\u00eddio a quem n\u00e3o necessita, e a falta de apoio para as pessoas que necessitam n\u00e3o somente de gratuidade, mas de apoio financeiro para continuar estudando.<\/p>\n<p>Como o gr\u00e1fico acima mostra, hoje o ensino superior p\u00fablico tem mais estudantes de baixa renda do que o privado, e menos pessoas de renda mais elevada. Ambos, por\u00e9m, cont\u00e9m predominantemente estudantes de renda alta &#8211; no setor p\u00fablico, 30% dos estudantes v\u00eam do d\u00e9cimo superior de renda familiar, e 53% dos dois d\u00e9cimos superiores, contra somente 2% dos dois d\u00e9cimos inferiores. No setor privado, as propor\u00e7\u00f5es s\u00e3o de 38%, 64% e 1.2%, respectivamente. Os mais ricos est\u00e3o come\u00e7ando a emigrar da educa\u00e7\u00e3o p\u00fablica  para a privada, como aconteceu anos atr\u00e1s com a educa\u00e7\u00e3o m\u00e9dia; mas ambos os setores continuam predominante ocupados por estudantes de fam\u00edlias de renda mais alta.<\/p>\n<p>Eu estou de acordo que existem muitas outras quest\u00f5es priorit\u00e1rias no ensino superior, como a busca de excel\u00eancia acad\u00eamica, a qualidade da educa\u00e7\u00e3o superior de massas, a diferencia\u00e7\u00e3o institucional, a avalia\u00e7\u00e3o, etc. Mas a introdu\u00e7\u00e3o do princ\u00edpio do pagamento serviria para deixar claro que a educa\u00e7\u00e3o superior p\u00fablica n\u00e3o \u00e9 um beneficio que a sociedade deve aos estudantes, mas um privil\u00e9gio que deve ser correspondido com senso de responsabilidade e retribui\u00e7\u00e3o.<span hidden class=\"__iawmlf-post-loop-links\" data-iawmlf-links=\"[{&quot;id&quot;:1158,&quot;href&quot;:&quot;http:\\\/\\\/bp3.blogger.com\\\/_QiS7NmwxcOc\\\/RvjhtL2RsNI\\\/AAAAAAAAADQ\\\/8fVNUDHLIUg\\\/s1600-h\\\/rendasup.jpg&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260416023457\\\/http:\\\/\\\/bp3.blogger.com\\\/_QiS7NmwxcOc\\\/RvjhtL2RsNI\\\/AAAAAAAAADQ\\\/8fVNUDHLIUg\\\/s1600-h\\\/rendasup.jpg&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-04-19 03:06:58&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-27 14:42:01&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-03 09:05:36&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-11 20:54:33&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-15 11:53:32&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-23 08:54:37&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-26 09:51:40&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-29 21:06:11&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-03 01:42:00&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-07 01:18:16&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-11 00:48:46&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-14 22:17:49&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-18 07:00:44&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-25 10:01:40&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-29 08:05:11&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-03 22:43:37&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-07 22:43:45&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-11 03:51:24&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-23 18:01:43&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-08-02 08:15:39&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-08-05 08:31:09&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-08-08 16:26:17&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-08-12 08:27:10&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-08-16 07:47:15&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-08-22 01:09:58&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-08-26 05:14:32&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-08-30 09:22:11&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-08-30 09:22:11&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1159,&quot;href&quot;:&quot;http:\\\/\\\/www.schwartzman.org.br\\\/simon\\\/poledsup.pdf&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260416025532\\\/http:\\\/\\\/www.schwartzman.org.br\\\/simon\\\/poledsup.pdf&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-04-19 17:26:50&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-27 15:29:09&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-05-03 09:05:38&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-05-11 20:54:36&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-05-15 11:53:24&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-05-24 17:14:26&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-05-29 21:06:11&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-06-03 01:42:06&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-06-07 01:18:20&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-06-11 00:48:46&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-06-14 22:17:51&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-06-18 07:00:45&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-06-25 15:15:44&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-06-29 08:05:11&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-07-03 22:43:34&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-07-10 19:47:30&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-07-23 18:01:45&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-07-30 03:38:16&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-08-02 08:15:38&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-08-05 08:31:09&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-08-08 16:26:18&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-08-12 08:27:09&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-08-16 07:47:15&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-08-22 05:44:49&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-08-26 17:12:15&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-09-01 16:18:50&quot;,&quot;http_code&quot;:206}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-09-01 16:18:50&quot;,&quot;http_code&quot;:206},&quot;process&quot;:&quot;done&quot;}]\"><\/span><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Convidado pelo PSDB, participei no dia 24 de setembro de um semin\u00e1rio sobre educa\u00e7\u00e3o, aonde fiz uma apresenta\u00e7\u00e3o que est\u00e1 dispon\u00edvel aqui, e que tem a vantagem de ter somente seis p\u00e1ginas. Creio que houve bastante consenso entre os participantes da mesa &#8211; C\u00e9sar S\u00e1 Barreto, Carlos Brito Cruz e Ab\u00edlio Baeta Neves &#8211; exceto &hellip; <a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/por-uma-nova-politica-de-educacao-superior\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Por uma nova pol\u00edtica de educa\u00e7\u00e3o superior&#8221;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[11],"tags":[],"class_list":["post-173","post","type-post","status-publish","format-standard","hentry","category-educacao-superior"],"_links":{"self":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/comments?post=173"}],"version-history":[{"count":2,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/173\/revisions"}],"predecessor-version":[{"id":7147,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/173\/revisions\/7147"}],"wp:attachment":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/media?parent=173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/categories?post=173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/tags?post=173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}