{"id":180,"date":"2007-11-07T06:08:00","date_gmt":"2007-11-07T09:08:00","guid":{"rendered":"http:\/\/www.schwartzman.org.br\/sitesimon\/?p=180"},"modified":"2022-12-15T20:08:46","modified_gmt":"2022-12-15T23:08:46","slug":"pobreza-populacao-e-desigualdade","status":"publish","type":"post","link":"https:\/\/www.schwartzman.org.br\/sitesimon\/pobreza-populacao-e-desigualdade\/","title":{"rendered":"Pobreza, popula\u00e7\u00e3o e desigualdade"},"content":{"rendered":"<p><script type='application\/json' class='__iawmlf-post-loop-links'>[{\"id\":1153,\"href\":\"http:\\\/\\\/bp2.blogger.com\\\/_QiS7NmwxcOc\\\/RzGElCdz8jI\\\/AAAAAAAAAEQ\\\/6ZLIMvr3PU8\\\/s1600-h\\\/medio.jpg\",\"archived_href\":\"https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260416023444\\\/http:\\\/\\\/bp2.blogger.com\\\/_QiS7NmwxcOc\\\/RzGElCdz8jI\\\/AAAAAAAAAEQ\\\/6ZLIMvr3PU8\\\/s1600-h\\\/medio.jpg\",\"redirect_href\":\"\",\"checks\":[{\"date\":\"2026-04-20 02:14:58\",\"http_code\":200},{\"date\":\"2026-04-25 08:50:38\",\"http_code\":200},{\"date\":\"2026-04-30 01:56:13\",\"http_code\":200},{\"date\":\"2026-05-05 14:31:10\",\"http_code\":200},{\"date\":\"2026-05-10 17:42:16\",\"http_code\":200}],\"broken\":false,\"last_checked\":{\"date\":\"2026-05-10 17:42:16\",\"http_code\":200},\"process\":\"done\"}]<\/script>Participei no dia 5 de novembro, em Belo Horizonte, do &#8220;Semin\u00e1rio sobre popula\u00e7\u00e3o, pobreza e desigualade&#8221;, organizado pela Associa\u00e7\u00e3o Brasileira de Estudos Poulacionais e a Comiss\u00e3o Nacional de Popula\u00e7\u00e3o e Desenvolvimento. Meu painel tinha o nome de &#8220;Din\u00e2mica populacional e as oportunidades de pol\u00edticas p\u00fablicas&#8221;, e foi coordenado por Eduardo Rios Neto.<\/p>\n<p>Dos tr\u00eas apresentadores, Eduardo Pereira, do Minist\u00e9rio da Previd\u00eancia Social, foi o \u00fanico que tratou efetivamente de din\u00e2mica populacional. Ele mostrou que, com o envelhecimento da popula\u00e7\u00e3o, o sistema previdenci\u00e1rio brasileiro \u00e9 insunstent\u00e1vel a longo prazo, porque haver\u00e1 um n\u00famero crescente de velhos recebendo benef\u00edcios para um n\u00famero decrescente de jovens. E que isto n\u00e3o muda com a economia crescendo, porque, se tiver mais gente pagando a previd\u00eancia hoje, haver\u00e1 mais gente tamb\u00e9m recebendo depois, e vivendo muito mais tempo. O Minist\u00e9rio preparou estes dados, na forma de v\u00e1rias simula\u00e7\u00f5es, para apresentar ao Forum Nacional da Previd\u00eancia Social, aonde est\u00e3o representados os sindicatos, aposentados, pensionistas, empregadores e o governo federal, e, pelo que parece, ningu\u00e9m l\u00e1 gostou da tese de que os benef\u00edcios da previd\u00eancia deveriam mudar. O problema \u00e9 que os principais interessados na reforma, nossos filhos, que v\u00e3o ter que pagar a conta ou conviver com um sistema previdenci\u00e1rio falido, n\u00e3o estavam presentes, e n\u00e3o havia ningu\u00e9m no f\u00f3rum, aparentemente, que defendesse seus interesses.<\/p>\n<p>O outro apresentador foi Pedro Olinto, do Banco Mundial, que antecipou os principais resultados de uma avalia\u00e7\u00e3o que o Banco est\u00e1 fazendo de um grande n\u00famero de programas de tipo Bolsa Fam\u00edlia que o Banco vem apoiando e incentivando em um n\u00famero crescente de pa\u00edses, inclusive o Brasil. O ponto principal foi mostrar como estes programas s\u00e3o, em geral, bem focalizados, e de fato melhoram em alguma medida as condi\u00e7\u00f5es de vida das popula\u00e7\u00f5es mais pobres. O que me pareceu mais novo foi a conclus\u00e3o de que os programas n\u00e3o tem impacto sobre o acesso \u00e0 escola em pa\u00edses em que a quase totalidade da popula\u00e7\u00e3o j\u00e1 est\u00e1 na educa\u00e7\u00e3o b\u00e1sica, como no Brasil; e que o impacto sobre a qualidade da educa\u00e7\u00e3o parece ser inclusive negativo. Eu j\u00e1 vinha dizendo e discutindo isto h\u00e1 v\u00e1rios anos, e fico contente em ver que agora o Banco Mundial reconhece isto. Ali\u00e1s, se entendi bem, a avalia\u00e7\u00e3o do bolsa fam\u00edlia brasileiro feita por Eduardo Rios-Neto mostra a mesma coisa.<\/p>\n<p><a onblur=\"try {parent.deselectBloggerImageGracefully();} catch(e) {}\" href=\"http:\/\/bp2.blogger.com\/_QiS7NmwxcOc\/RzGElCdz8jI\/AAAAAAAAAEQ\/6ZLIMvr3PU8\/s1600-h\/medio.jpg\"><\/a><\/p>\n<p>Em minha apresenta\u00e7\u00e3o, eu mostrei dados da PNAD sobre a evolu\u00e7\u00e3o da educa\u00e7\u00e3o brasileira nos diferentes n\u00edveis, e discuti um pouco sobre cada um deles e sobre as prioridades. Um dos dados que mostrei foi como o acesso ao ensino m\u00e9dio, que havia crescido muito na d\u00e9cada de 90, parece estar estacionando a um n\u00edvel muito baixo, inferior a 60% de cobertura nas regi\u00f5es mais ricas (veja o gr\u00e1fico), quando dever\u00edamos estar caminhando para os 100%, e isto sem falar na qualidade, que, por tudo que sabemos, est\u00e1 muito mal. A expans\u00e3o do ensino superior, enquanto isto, parece ser a prioridade do governo federal, sem preocupa\u00e7\u00e3o aparente com sua qualidade, o que parece ser um erro evidente de foco.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Participei no dia 5 de novembro, em Belo Horizonte, do &#8220;Semin\u00e1rio sobre popula\u00e7\u00e3o, pobreza e desigualade&#8221;, organizado pela Associa\u00e7\u00e3o Brasileira de Estudos Poulacionais e a Comiss\u00e3o Nacional de Popula\u00e7\u00e3o e Desenvolvimento. Meu painel tinha o nome de &#8220;Din\u00e2mica populacional e as oportunidades de pol\u00edticas p\u00fablicas&#8221;, e foi coordenado por Eduardo Rios Neto. Dos tr\u00eas apresentadores, &hellip; <a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/pobreza-populacao-e-desigualdade\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Pobreza, popula\u00e7\u00e3o e desigualdade&#8221;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[8],"tags":[],"class_list":["post-180","post","type-post","status-publish","format-standard","hentry","category-politica-social"],"_links":{"self":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/comments?post=180"}],"version-history":[{"count":2,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/180\/revisions"}],"predecessor-version":[{"id":7148,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/180\/revisions\/7148"}],"wp:attachment":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/media?parent=180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/categories?post=180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/tags?post=180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}