{"id":184,"date":"2007-12-23T06:46:00","date_gmt":"2007-12-23T09:46:00","guid":{"rendered":"http:\/\/www.schwartzman.org.br\/sitesimon\/?p=184"},"modified":"2008-08-03T10:15:03","modified_gmt":"2008-08-03T13:15:03","slug":"o-enem-brasileiro-e-o-gcse-ingles","status":"publish","type":"post","link":"https:\/\/www.schwartzman.org.br\/sitesimon\/o-enem-brasileiro-e-o-gcse-ingles\/","title":{"rendered":"O ENEM brasileiro e o GCSE ingl\u00eas"},"content":{"rendered":"<p><script type='application\/json' class='__iawmlf-post-loop-links'>[{\"id\":1151,\"href\":\"http:\\\/\\\/news.bbc.co.uk\\\/2\\\/hi\\\/uk_news\\\/education\\\/7155843.stm\",\"archived_href\":\"https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260416023505\\\/http:\\\/\\\/news.bbc.co.uk\\\/2\\\/hi\\\/uk_news\\\/education\\\/7155843.stm\",\"redirect_href\":\"\",\"checks\":[{\"date\":\"2026-04-19 18:20:07\",\"http_code\":200},{\"date\":\"2026-04-23 09:21:05\",\"http_code\":200},{\"date\":\"2026-04-26 23:12:26\",\"http_code\":200},{\"date\":\"2026-05-01 21:46:23\",\"http_code\":200},{\"date\":\"2026-05-05 12:30:58\",\"http_code\":200},{\"date\":\"2026-05-10 17:42:18\",\"http_code\":200}],\"broken\":false,\"last_checked\":{\"date\":\"2026-05-10 17:42:18\",\"http_code\":200},\"process\":\"done\"}]<\/script>Enquanto no Brasil se comemora a expans\u00e3o do ENEM, o Exame Nacional do Ensino M\u00e9dio, com 2.7 milh\u00f5es de participantes em 2007, a Inglaterra abandona o projeto de criar um Diploma Geral para o  ensino m\u00e9dio associado ao \u201cGeneral Certificate of Secondary Education\u201d (GSCE), que deveria certificar a obten\u00e7\u00e3o de compet\u00eancias gerais dos estudantes de n\u00edvel m\u00e9dio naquele pa\u00eds. Quem est\u00e1 errado?<\/p>\n<p>A raz\u00e3o pela qual os ingleses est\u00e3o abandonando o diploma geral, segundo a <a href=\"http:\/\/news.bbc.co.uk\/2\/hi\/uk_news\/education\/7155843.stm\">not\u00edcia da BBC,<\/a> \u00e9 que ele poderia entrar em conflito e desqualificar uma s\u00e9rie de diplomas profissionais e t\u00e9cnicos que est\u00e3o sendo promovidos pelos diversos minist\u00e9rios daquele pa\u00eds. O ENEM foi saudado, inclusive por mim, como uma importante tentativa de estabelecer um padr\u00e3o de qualidade para o ensino m\u00e9dio brasileiro que n\u00e3o existia at\u00e9 ent\u00e3o, cumprindo uma fun\u00e7\u00e3o semelhante \u00e0 do <span style=\"font-style: italic;\">SAT Reasoning Test <\/span>nos Estados Unidos e os exames nacionais europeus como o <span style=\"font-style: italic;\">Abitur <\/span>alem\u00e3o e o <span style=\"font-style: italic;\">Baccalaur\u00e9at <\/span>franc\u00eas. Eles buscam medir habilidades gen\u00e9ricas, associadas sobretudo \u00e0 capacidade de leitura, escrita e de uso de matem\u00e1tica, consideradas criticas para todo o tipo de forma\u00e7\u00e3o.<\/p>\n<p>O problema com estes tipos de exame (mesmo supondo que eles sejam tecnicamente bem feitos, o que n\u00e3o \u00e9 claro no caso do ENEM) \u00e9 que eles dividem os estudantes em duas categorias: os acad\u00eamicos e generalistas, que v\u00e3o para as universidades e entram nas carreiras mais prestigiadas, e os t\u00e9cnicos e especialistas, menos capacitados, que ficam em atividades de menor prest\u00edgio e remunera\u00e7\u00e3o. A maioria dos paises europeus, como a Alemanha e a Fran\u00e7a, estabeleceu estas divis\u00f5es muito tempo atr\u00e1s (o <span style=\"font-style: italic;\">Abitur<\/span> alem\u00e3o \u00e9 do s\u00e9culo XVIII), e foram muitas vezes bem sucedidos em proporcionar uma capacita\u00e7\u00e3o de qualidade para os que seguiam o caminho das profiss\u00f5es t\u00e9cnicas, sobretudo nos pa\u00edses germ\u00e2nicos. Em muitos outros paises, no entanto, e inclusive na Am\u00e9rica Latina, esta divis\u00e3o acabou criando um sistema educacional divido entre um ensino para a elite e outro para o povo, em geral de p\u00e9ssima qualidade.  Hoje, a tend\u00eancia nos paises europeus \u00e9 substituir os antigos sistemas duais por uma pluralidade de exames e qualifica\u00e7\u00f5es, ao mesmo tempo em que se reconhece que todos eles requerem n\u00edveis adequados de compet\u00eancia de leitura, escrita e matem\u00e1tica.<\/p>\n<p>No Brasil se fala muito em ensino t\u00e9cnico, de vez em quando se tomam algumas iniciativas, mas at\u00e9 hoje n\u00e3o come\u00e7amos a discutir a s\u00e9rio que tipo de forma\u00e7\u00e3o o ensino m\u00e9dio deveria proporcionar. Se os ingleses est\u00e3o certos, pareceria que o ENEM est\u00e1 na contram\u00e3o.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Enquanto no Brasil se comemora a expans\u00e3o do ENEM, o Exame Nacional do Ensino M\u00e9dio, com 2.7 milh\u00f5es de participantes em 2007, a Inglaterra abandona o projeto de criar um Diploma Geral para o ensino m\u00e9dio associado ao \u201cGeneral Certificate of Secondary Education\u201d (GSCE), que deveria certificar a obten\u00e7\u00e3o de compet\u00eancias gerais dos estudantes de &hellip; <a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/o-enem-brasileiro-e-o-gcse-ingles\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;O ENEM brasileiro e o GCSE ingl\u00eas&#8221;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[22,7],"tags":[],"class_list":["post-184","post","type-post","status-publish","format-standard","hentry","category-educacao","category-educacao-basica"],"_links":{"self":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/comments?post=184"}],"version-history":[{"count":1,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/184\/revisions"}],"predecessor-version":[{"id":311,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/184\/revisions\/311"}],"wp:attachment":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/media?parent=184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/categories?post=184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/tags?post=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}