{"id":2131,"date":"2011-03-20T19:01:46","date_gmt":"2011-03-20T22:01:46","guid":{"rendered":"http:\/\/www.schwartzman.org.br\/sitesimon\/?p=2131"},"modified":"2020-10-13T11:10:26","modified_gmt":"2020-10-13T14:10:26","slug":"a-secretaria-municipal-de-educacao-do-rio-de-janeiro-e-as-tics","status":"publish","type":"post","link":"https:\/\/www.schwartzman.org.br\/sitesimon\/a-secretaria-municipal-de-educacao-do-rio-de-janeiro-e-as-tics\/","title":{"rendered":"A Secretaria Municipal de Educa\u00e7\u00e3o do Rio de Janeiro e as TICs"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><em>Rafael Parente, Subsecret\u00e1rio de Projetos Estrat\u00e9gicos da Secretaria Municipal de Educa\u00e7\u00e3o da cidade do Rio de Janeiro enviou a nota abaixo a respeito das atividades da Secretaria na \u00e1rea das novas tecnologia de informa\u00e7\u00e3o e comunica\u00e7\u00e3o:<\/em><\/p>\n<p><strong>Assumindo a responsabilidade e aumentando a transpar\u00eancia: como estamos usando as novas tecnologias nas escolas da cidade do Rio de Janeiro<\/strong><em><br \/>\n<\/em><\/p>\n<p><strong> <\/strong><\/p>\n<p>O nosso programa de utiliza\u00e7\u00e3o das novas tecnologias de informa\u00e7\u00e3o e comunica\u00e7\u00e3o (TICs) para melhorar a aprendizagem nas escolas da cidade do Rio de Janeiro pode ser dividido em tr\u00eas partes principais: 1) Infra-estrutura e manuten\u00e7\u00e3o; 2) Capacita\u00e7\u00e3o; 3) Sistemas e conte\u00fados.<\/p>\n<p>Com rela\u00e7\u00e3o \u00e0 infra-estrutura e manuten\u00e7\u00e3o, sabemos que n\u00e3o poder\u00edamos investir no aumento do parque tecnol\u00f3gico sem antes pensarmos em dois outros aspectos: quest\u00f5es el\u00e9tricas e quest\u00f5es de seguran\u00e7a. Todas as escolas est\u00e3o recebendo reformas el\u00e9tricas e l\u00f3gicas. Para lidar com quest\u00f5es de seguran\u00e7a, estamos aumentando o pessoal de apoio, instalando c\u00e2meras e alarmes e inserindo, nos netbooks, dispositivos para que eles sejam bloqueados quando retirados da rede da escola. O servi\u00e7o de manuten\u00e7\u00e3o dos equipamentos e da rede, que j\u00e1 era feita por uma empresa especializada, est\u00e1 sendo aumentado. Tamb\u00e9m j\u00e1 temos manuten\u00e7\u00e3o por acesso remoto.<\/p>\n<p>A pesquisa do Centro Edelstein de Pesquisas Sociais foi realizada durante o ano de 2009. Como houve uma intensifica\u00e7\u00e3o das a\u00e7\u00f5es voltadas para a \u00e1rea em 2010, consideramos que certos aspectos do resultado da pesquisa n\u00e3o mais refletem a realidade. Das 1064 escolas da rede, 1060 t\u00eam banda larga de 1 ou 2MB. Sabemos que essa velocidade n\u00e3o \u00e9 suficiente e estamos realizando uma licita\u00e7\u00e3o para uma internet mais potente. Roteadores est\u00e3o sendo instalados para que os links sejam transformados em internet sem fio. Todas as escolas t\u00eam de 5 a 30 computadores para utiliza\u00e7\u00e3o dos alunos. Quando n\u00e3o h\u00e1 um laborat\u00f3rio de inform\u00e1tica, eles est\u00e3o nas salas de leitura ou nas salas de aula. Quase 80% dos computadores antigos ou que n\u00e3o estavam funcionando j\u00e1 foram substitu\u00eddos. Alunos do oitavo ano est\u00e3o constantemente sendo treinados para exercerem o papel de alunos monitores, sendo respons\u00e1veis pelos laborat\u00f3rios de inform\u00e1tica de suas escolas no turno contr\u00e1rio \u00e0s suas aulas, duas vezes por semana.<\/p>\n<p>Sabemos, no entanto, que o tamanho da sala do laborat\u00f3rio e o n\u00famero de m\u00e1quinas por vezes n\u00e3o atende \u00e0s necessidades. \u00c9 por isso que decidimos investir num modelo diferente. Todas as salas de 6\u00ba a 9\u00ba anos est\u00e3o recebendo netbooks, projetores e caixas de som. Os netbooks s\u00e3o conectados \u00e0 internet sem fio e as aulas da Educop\u00e9dia (com v\u00eddeos, textos, jogos e podcasts) s\u00e3o projetadas sobre quadros brancos ou tel\u00f5es. Al\u00e9m disso, teremos netbooks para utiliza\u00e7\u00e3o dos alunos dentro de suas salas de aula regulares, um por aluno, em uma aula a cada tr\u00eas.<\/p>\n<p>No que diz respeito \u00e0 capacita\u00e7\u00e3o de professores, \u00e9 importante citar resultados de duas outras pesquisas realizadas ao longo de 2010. Uma, do Instituto Desiderata, concluiu que professores n\u00e3o s\u00f3 desejam utilizar mais computadores conectados, mas tamb\u00e9m que acreditam que novas tecnologias e novas m\u00eddias s\u00e3o elementos essenciais para que \u201ca escola se torne um lugar melhor para estudar e ensinar\u201d. Isso sugere que investimentos bem planejados nessa \u00e1rea afetam positivamente a motiva\u00e7\u00e3o desses profissionais (pesquisas internacionais tamb\u00e9m asseguram impactos nas motiva\u00e7\u00f5es de professores e alunos, essenciais para a melhoria da qualidade da educa\u00e7\u00e3o).<\/p>\n<p>A segunda pesquisa, do Instituto Oi Futuro, com o apoio do Ibope e do Instituto Paulo Montenegro, aplicou mais de 35 mil question\u00e1rios, com o objetivo de compreender o relacionamento dos alunos, professores e diretores com as novas tecnologias. Essa pesquisa verificou que mais de 80% dos professores consideram que capacita\u00e7\u00f5es relacionadas \u00e0 utiliza\u00e7\u00e3o das TICs s\u00e3o as mais importantes para sua atua\u00e7\u00e3o profissional. Congruente com os resultados do Centro Edelstein, tamb\u00e9m concluiu que os professores j\u00e1 est\u00e3o familiarizados com o uso de computadores e da internet, mas que o perfil de compet\u00eancias para essa utiliza\u00e7\u00e3o varia muito, de onde conclu\u00edmos que precisamos de cursos com n\u00edveis e objetivos diferentes. Por isso, come\u00e7amos a oferecer capacita\u00e7\u00f5es pela MultiRio e em parceria com o MEC e empresas e institutos, como a Microsoft e a Intel. \u00c9 importante dizer que, a partir de 2010, passamos a ter uma semana de capacita\u00e7\u00e3o para todos os profissionais da rede antes do in\u00edcio do ano letivo.<\/p>\n<p>No que tange a sistemas e conte\u00fados, estamos integrando sistemas e atualizando processos para diminuir a burocracia que rouba tempo da dire\u00e7\u00e3o das escolas e nos debru\u00e7ando frequentemente sobre os dados gerados com avalia\u00e7\u00f5es. Estamos convidando universidades e institutos para nos ajudar a transformar esses dados em intelig\u00eancia que nos auxilie a tomar decis\u00f5es futuras. Al\u00e9m disso, a partir de um curr\u00edculo claro, j\u00e1 disseminado amplamente na rede, criamos nosso pr\u00f3prio sistema de ensino, com apostilas e a <a href=\"http:\/\/www.educopedia.com.br\" target=\"_blank\" rel=\"noopener noreferrer\">Educop\u00e9dia<\/a>. Essa plataforma inclui n\u00e3o apenas as aulas digitais j\u00e1 citadas, divididas em temas para todos os anos e todas as disciplinas, mas apresenta\u00e7\u00f5es de PowerPoint e planos de aula, com justificativas da import\u00e2ncia dos temas e dicas pr\u00e1ticas de como o tema pode ser abordado em sala de aula. As apostilas e a Educop\u00e9dia s\u00e3o criadas e constantemente revisadas pelos professores da rede, com a supervis\u00e3o de consultores e institui\u00e7\u00f5es parceiras. O curr\u00edculo, as apostilas, a Educop\u00e9dia e as provas bimestrais s\u00e3o completamente congruentes. A Educop\u00e9dia tamb\u00e9m ser\u00e1 utilizada para capacita\u00e7\u00f5es a dist\u00e2ncia, o que diminuir\u00e1 consideravelmente os custos.<\/p>\n<p>Grande parte das a\u00e7\u00f5es dessa gest\u00e3o est\u00e1 sendo acompanhada e avaliada por organiza\u00e7\u00f5es como o Banco Mundial e a Unesco e por pesquisadores acad\u00eamicos e institutos. Novas pol\u00edticas s\u00e3o discutidas e planejadas com base em pesquisas nacionais e internacionais, sempre com objetivos e metas claras. As a\u00e7\u00f5es relacionadas \u00e0s TICs n\u00e3o exclui (e, por vezes, complementa) um universo de outras a\u00e7\u00f5es, como melhoria da alfabetiza\u00e7\u00e3o, aumento de vagas em creches, reformas de escolas, realfabetiza\u00e7\u00e3o e acelera\u00e7\u00e3o de alunos com defasagem idade\/s\u00e9rie, etc.<\/p>\n<p>Finalizo contando que estamos em contato direto com os profissionais da rede presencialmente e virtualmente. Via Twitter, a secret\u00e1ria Claudia Costin e toda a equipe se comunica todos os dias com mais de 8 mil profissionais da rede. Temos visitado pelo menos 10 escolas por semana, verificando o andamento das a\u00e7\u00f5es e conversando com alunos, professores e diretores. O clima \u00e9 de otimismo e os resultados at\u00e9 agora t\u00eam sido muito bons. Estamos \u00e0 disposi\u00e7\u00e3o para mais esclarecimentos e convidamos os interessados a visitarem as escolas conosco para verificarem essa transforma\u00e7\u00e3o positiva de perto.<\/p>\n<p>Algumas pesquisas interessantes (nacionais e internacionais) sobre TICs, motiva\u00e7\u00e3o e capacita\u00e7\u00e3o:<\/p>\n<p>http:\/\/download.intel.com\/education\/wsis\/ICT_Education_Reform_Economic_Growth.pdf<\/p>\n<p>http:\/\/www.senac.br\/BTS\/353\/artigo-02.pdf<\/p>\n<p>http:\/\/www.infodev.org\/en\/Publication.157.html<\/p>\n<p>http:\/\/www.canterbury.ac.uk\/education\/protected\/spss\/docs\/motivational-effect-ict-brief.pdf<\/p>\n<p>http:\/\/www.saum.uvigo.es\/reec\/volumenes\/volumen8\/ART8_Vol8_N2.pdf<\/p>\n<p>http:\/\/ww.aedb.br\/seget\/artigos07\/1165_EGC%205003%20artigo%20final%20V0.3.pdf<\/p>\n<p>http:\/\/www.distanceandaccesstolearning.net\/contents\/IRRODL-Robinson.pdf<\/p>\n<p>http:\/\/onlinelibrary.wiley.com\/doi\/10.1111\/j.1465-3435.2006.00274.x\/full<\/p>\n<p>http:\/\/www.editlib.org\/noaccess\/5339<\/p>\n<p>http:\/\/www.e-journalofeducation.com\/main\/ICT\/kenruthven.pdf<span hidden class=\"__iawmlf-post-loop-links\" data-iawmlf-links=\"[{&quot;id&quot;:673,&quot;href&quot;:&quot;http:\\\/\\\/www.educopedia.com.br&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;}]\"><\/span><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Rafael Parente, Subsecret\u00e1rio de Projetos Estrat\u00e9gicos da Secretaria Municipal de Educa\u00e7\u00e3o da cidade do Rio de Janeiro enviou a nota abaixo a respeito das atividades da Secretaria na \u00e1rea das novas tecnologia de informa\u00e7\u00e3o e comunica\u00e7\u00e3o: Assumindo a responsabilidade e aumentando a transpar\u00eancia: como estamos usando as novas tecnologias nas escolas da cidade do &hellip; <a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/a-secretaria-municipal-de-educacao-do-rio-de-janeiro-e-as-tics\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;A Secretaria Municipal de Educa\u00e7\u00e3o do Rio de Janeiro e as TICs&#8221;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[7],"tags":[],"class_list":["post-2131","post","type-post","status-publish","format-standard","hentry","category-educacao-basica"],"_links":{"self":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/2131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/comments?post=2131"}],"version-history":[{"count":8,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/2131\/revisions"}],"predecessor-version":[{"id":6604,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/2131\/revisions\/6604"}],"wp:attachment":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/media?parent=2131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/categories?post=2131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/tags?post=2131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}