{"id":2138,"date":"2011-03-22T06:21:39","date_gmt":"2011-03-22T09:21:39","guid":{"rendered":"http:\/\/www.schwartzman.org.br\/sitesimon\/?p=2138"},"modified":"2011-03-22T06:23:38","modified_gmt":"2011-03-22T09:23:38","slug":"ainda-as-icts-no-rio-de-janeiro","status":"publish","type":"post","link":"https:\/\/www.schwartzman.org.br\/sitesimon\/ainda-as-icts-no-rio-de-janeiro\/","title":{"rendered":"Ainda as ICTs no Rio de Janeiro"},"content":{"rendered":"<p><em>Escrevem Bernardo Sorj e Mauricio Lissovsky, sobre o <a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/?p=2131&amp;lang=pt-br\" target=\"_blank\">coment\u00e1rio de Rafael Parente<\/a> \u00e0 <a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/?p=2122&amp;lang=pt-br\" target=\"_blank\">pesquisa que realizaram <\/a>sobre o uso das tecnologias de informa\u00e7\u00e3o e comunica\u00e7\u00e3o nas esolas municipais do Rio de Janeiro:<\/em><\/p>\n<p>1) \u00a0 \u00a0 Nossa pesquisa \u00a0n\u00e3o pretende avaliar a atua\u00e7\u00e3o da \u00a0Secretaria de Educa\u00e7\u00e3o, nem no passado, nem no presente. \u00a0Para tanto ter\u00edamos necessidade de uma serie hist\u00f3rica que permitissem compara\u00e7\u00f5es. Nosso objetivo limitou-se, \u00a0 a \u00a0partir das percep\u00e7\u00f5es e atitudes dos professores que responderam o question\u00e1rio, a \u00a0identificar problemas e contribuir para a sua solu\u00e7\u00e3o. N\u00e3o procuramos \u00a0verificar qual \u00e9 a porcentagem de escolas com laborat\u00f3rios ou em quantos deles h\u00e1 conex\u00e3o eficiente com a Internet. Visava antes perceber de que modo \u00a0estes e outros \u00a0fatores \u00a0s\u00e3o percebidos pelos professores e de que modo afetam o uso que fazem da inform\u00e1tica em suas escolas e na rela\u00e7\u00e3o com os \u00a0alunos.<\/p>\n<p>2) \u00a0 \u00a0Rafael Parente menciona o estudo da Oi Futuro e do Instituto Desiderata. Procuramos obter os resultados e os question\u00e1rios utilizados. Sem resultado. Ele menciona que a pesquisa da Oi Futuro indica que mais de 80% dos professores consideram que capacita\u00e7\u00f5es relacionadas \u00e0 utiliza\u00e7\u00e3o das TICs s\u00e3o as mais importantes para sua atua\u00e7\u00e3o profissional. \u00a0E que a pesquisa da Desiderata \u201cconcluiu que professores n\u00e3o s\u00f3 desejam utilizar mais computadores conectados, mas tamb\u00e9m que acreditam que novas tecnologias e novas m\u00eddias s\u00e3o elementos essenciais para que \u201ca escola se torne um lugar melhor para estudar e ensinar\u201d. \u00a0S\u00e3o \u00a0afirma\u00e7\u00f5es fortes, e n\u00e3o \u00a0tendo acesso aos \u00a0question\u00e1rios e a forma \u00a0em que foram elaboradas as perguntas \u00a0(que como sabemos influenciam a resposta) fica dif\u00edcil mensurar exatamente o que elas revelam. \u00a0 Na nossa pesquisa n\u00e3o perguntamos a relev\u00e2ncia que os professores atribuem \u00e0 capacita\u00e7\u00e3o (afinal qualquer valor inferior a 80% entre professores, seria surpreendente!). \u00a0Est\u00e1vamos antes interessados em saber que influ\u00eancia tiveram as capacita\u00e7\u00f5es na frequ\u00eancia do uso \u00a0dos recursos de inform\u00e1tica educativa nas escolas. E a resposta que alcan\u00e7amos aqui, por exemplo, \u00e9 que as capacita\u00e7\u00f5es realizadas at\u00e9 2009 tiveram algum impacto positivo entre os professores do primeiro segmento, apenas. No que diz respeito ao conjunto do professorado, o dom\u00ednio de ferramentas de internet pelo professor (independente de onde tenha adquirido este dom\u00ednio) mostrou-se mais determinante que outros fatores. \u00a0Seria poss\u00edvel \u00a0comparar melhor \u00a0os resultados se \u00a0fossem disponibilizados os materiais das \u00a0pesquisas realizadas pela Oi Futuro e Desiderata.<\/p>\n<p>3) Nossa pesquisa foi realizada a fins de 2009. Por mais que uma gest\u00e3o competente possa realizar em um ano (na verdade menos, pois a pesquisa da Oi futuro foi feita no segundo semestre de \u00a02010), \u00e9 bastante improv\u00e1vel que mudan\u00e7as radicais (a n\u00e3o ser, eventualmente, as da \u00a0infraestrutura f\u00edsica) possam \u00a0ter ocorrido no que diz respeito \u00e0 apropria\u00e7\u00e3o destes recursos pelos professores, a intensidade do uso dos equipamentos, etc. \u00a0Afinal, o processo de internaliza\u00e7\u00e3o de uma &#8220;inform\u00e1tica educativa&#8221; nas escolas do munic\u00edpio teve in\u00edcio h\u00e1 quase 15 anos e se trata de \u00a0um processo de longa dura\u00e7\u00e3o. \u00a0Inclusive porque, como indicamos no nosso artigo, deve enfrentar um grupo de professores que ter\u00e1 dificuldades de adapta\u00e7\u00e3o.<\/p>\n<p>4) O mais importante, a nosso ver, \u00e9 evitar que o debate sobre politicas publicas \u00a0 tome a forma de \u00a0criticas destrutivas (ou interpretadas como tais) \u00a0feitas pelos que est\u00e3o \u00a0\u201cfora\u201d \u00a0 e \u00a0defesas ufanistas do que est\u00e1 sendo feito \u00a0pelos \u00a0que est\u00e3o \u201cdentro\u201d \u00a0do aparelho publico. \u00a0Nosso estudo visa \u00a0melhorar o trabalho realizado pelas institui\u00e7\u00f5es \u00a0p\u00fablicas, que implica em identificar problemas e abrir o debate sobre um tema extremamente complexo, \u00a0como \u00e9 uso da inform\u00e1tica nas escolas, sobre o qual existem mais interrogantes que respostas. Estudos feitos por agentes externos ao aparelho estatal s\u00e3o fundamentais \u00a0 para \u00a0aumentar a \u00a0credibilidade, a transpar\u00eancia e a qualidade das politicas p\u00fablicas, e \u00a0visam \u00a0o dialogo, n\u00e3o o \u00a0confronto ou atitudes defensivas.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Escrevem Bernardo Sorj e Mauricio Lissovsky, sobre o coment\u00e1rio de Rafael Parente \u00e0 pesquisa que realizaram sobre o uso das tecnologias de informa\u00e7\u00e3o e comunica\u00e7\u00e3o nas esolas municipais do Rio de Janeiro: 1) \u00a0 \u00a0 Nossa pesquisa \u00a0n\u00e3o pretende avaliar a atua\u00e7\u00e3o da \u00a0Secretaria de Educa\u00e7\u00e3o, nem no passado, nem no presente. \u00a0Para tanto ter\u00edamos &hellip; <a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/ainda-as-icts-no-rio-de-janeiro\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Ainda as ICTs no Rio de Janeiro&#8221;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-2138","post","type-post","status-publish","format-standard","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/2138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/comments?post=2138"}],"version-history":[{"count":2,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/2138\/revisions"}],"predecessor-version":[{"id":2140,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/2138\/revisions\/2140"}],"wp:attachment":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/media?parent=2138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/categories?post=2138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/tags?post=2138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}