{"id":4540,"date":"2013-07-05T22:23:25","date_gmt":"2013-07-06T01:23:25","guid":{"rendered":"http:\/\/www.schwartzman.org.br\/sitesimon\/?p=4540"},"modified":"2013-07-05T22:24:36","modified_gmt":"2013-07-06T01:24:36","slug":"andre-lara-resende-o-mal-estar-contemporeano","status":"publish","type":"post","link":"https:\/\/www.schwartzman.org.br\/sitesimon\/andre-lara-resende-o-mal-estar-contemporeano\/","title":{"rendered":"Andr\u00e9 Lara Resende: O Mal-Estar Contempor\u00eaano"},"content":{"rendered":"<p><script type='application\/json' class='__iawmlf-post-loop-links'>[{\"id\":474,\"href\":\"http:\\\/\\\/www.valor.com.br\\\/cultura\\\/3187036\\\/o-mal-estar-contemporaneo\",\"archived_href\":\"https:\\\/\\\/web-wp.archive.org\\\/web\\\/20140809231601\\\/http:\\\/\\\/www.valor.com.br\\\/cultura\\\/3187036\\\/o-mal-estar-contemporaneo\",\"redirect_href\":\"https:\\\/\\\/www.valor.com.br\\\/cultura\\\/3187036\\\/o-mal-estar-contemporaneo\",\"checks\":[{\"date\":\"2026-04-16 17:54:05\",\"http_code\":206},{\"date\":\"2026-04-20 02:28:51\",\"http_code\":503},{\"date\":\"2026-04-24 14:06:08\",\"http_code\":206},{\"date\":\"2026-04-27 23:23:58\",\"http_code\":206},{\"date\":\"2026-05-01 17:28:51\",\"http_code\":206},{\"date\":\"2026-05-05 15:01:57\",\"http_code\":206},{\"date\":\"2026-05-09 03:16:03\",\"http_code\":206},{\"date\":\"2026-05-12 22:05:46\",\"http_code\":206}],\"broken\":false,\"last_checked\":{\"date\":\"2026-05-12 22:05:46\",\"http_code\":206},\"process\":\"done\"}]<\/script>De tudo que li nestas semanas sobre o sentido das manifesta\u00e7\u00f5es de rua no Brasil, este texto de Andr\u00e9 Lara Resende, Publicado no <a href=\"http:\/\/www.valor.com.br\/cultura\/3187036\/o-mal-estar-contemporaneo\" target=\"_blank\">Valor Econ\u00f4mico de 5 de julho<\/a>, \u00e9 provavelmente o que melhor interpreta o que vem ocorrendo, e por isto precisa ser lido com muita aten\u00e7\u00e3o e compartido. Estou fazendo minha parte.<\/p>\n<p style=\"text-align: center;\"><strong>O mal-estar contempor\u00e2neo<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Por Andr\u00e9 Lara Resende\u00a0<\/strong><\/p>\n<p>Nenhuma lideran\u00e7a soube captar e expressar o mal-estar contempor\u00e2neo. Este \u00e9 provavelmente o seu elemento novo: a internet viabiliza a mobiliza\u00e7\u00e3o antes que surjam as lideran\u00e7as<\/p>\n<p>Na tentativa de interpretar o protesto das ruas nas grandes cidades brasileiras, h\u00e1 uma natural tenta\u00e7\u00e3o de fazer um paralelo com os movimentos similares nos pa\u00edses avan\u00e7ados, sobretudo da Europa, mas tamb\u00e9m nos EUA &#8211; Occupy Wall Street &#8211; assim como com os da chamada Primavera \u00c1rabe. As condi\u00e7\u00f5es objetivas s\u00e3o, contudo, muito distintas. A Primavera \u00c1rabe \u00e9 um fen\u00f4meno de pa\u00edses totalit\u00e1rios, onde n\u00e3o h\u00e1 representa\u00e7\u00e3o democr\u00e1tica. N\u00e3o \u00e9 o caso do Brasil. Na Europa, sobretudo nos pa\u00edses mediterr\u00e2neos perif\u00e9ricos mais atingidos pelos efeitos da crise financeira de 2008, houve uma dr\u00e1stica piora das condi\u00e7\u00f5es de vida. O desemprego, especialmente entre os jovens, subiu para n\u00edveis dram\u00e1ticos. Mais uma vez, n\u00e3o \u00e9 o caso do Brasil.<\/p>\n<p>Nem os cr\u00edticos mais radicais ousariam argumentar que o Brasil de hoje n\u00e3o se enquadra nos moldes das democracias representativas do s\u00e9culo XX. Podem-se culpar os desacertos da pol\u00edtica econ\u00f4mica nos \u00faltimos seis anos. Embora devam ficar mais evidentes daqui para a frente, os efeitos negativos da incompet\u00eancia da pol\u00edtica econ\u00f4mica s\u00f3 muito recentemente se fizeram sentir. Fato \u00e9 que, desde a estabiliza\u00e7\u00e3o do processo inflacion\u00e1rio cr\u00f4nico, houve grandes avan\u00e7os nas condi\u00e7\u00f5es econ\u00f4micas de vida dos brasileiros. Nos \u00faltimos 20 anos, houve ganho substancial de renda entre os mais pobres. Ao contr\u00e1rio do que ocorreu em outras partes do mundo, at\u00e9 mesmo nos pa\u00edses avan\u00e7ados, a distribui\u00e7\u00e3o de renda melhorou. O desemprego est\u00e1 em seu m\u00ednimo hist\u00f3rico.<\/p>\n<p>\u00c9 verdade que a infla\u00e7\u00e3o, especialmente a de alimentos, que se faz sentir mais intensamente pelos assalariados, est\u00e1 em alta. Por mais consciente que se seja em rela\u00e7\u00e3o aos riscos, pol\u00edticos e econ\u00f4micos, da infla\u00e7\u00e3o, \u00e9 dif\u00edcil atribuir \u00e0 infla\u00e7\u00e3o o papel de catalisadora do movimento das ruas nas \u00faltimas semanas. S\u00f3 agora a taxa de infla\u00e7\u00e3o superou o teto da banda &#8211; excessivamente generosa, \u00e9 verdade &#8211; da meta do Banco Central.<\/p>\n<p>Os dois elementos tradicionais da insatisfa\u00e7\u00e3o popular &#8211; dificuldades econ\u00f4micas e falta de representa\u00e7\u00e3o democr\u00e1tica &#8211; definitivamente n\u00e3o est\u00e3o presentes no Brasil de hoje. Infla\u00e7\u00e3o, desemprego, autoritarismo e falta de liberdade de express\u00e3o n\u00e3o podem ser invocados para explicar a explos\u00e3o popular. O fen\u00f4meno \u00e9, portanto, novo. Procurar interpret\u00e1-lo de acordo com os c\u00e2nones do passado parece-me o caminho certo para n\u00e3o o compreender.<\/p>\n<p>O movimento de maio de 1968 na Fran\u00e7a tem sido lembrado diante das manifesta\u00e7\u00f5es das \u00faltimas semanas. O paralelo se justifica, pois maio de 68 \u00e9 o paradigma do movimento sem causas claras nem objetivos bem definidos, uma combust\u00e3o espont\u00e2nea surpreendente, que ocorre em condi\u00e7\u00f5es pol\u00edticas e econ\u00f4micas relativamente favor\u00e1veis. Movimento que, uma vez detonado, canaliza um sentimento de frustra\u00e7\u00e3o difusa &#8211; um &#8220;malaise&#8221;- com o estado das coisas, com tudo e todos, com a vida em geral.<\/p>\n<p>A novidade mais evidente em rela\u00e7\u00e3o a maio de 68 na Fran\u00e7a \u00e9 a internet e as redes sociais. Embora n\u00e3o tivesse express\u00e3o clara na vida p\u00fablica francesa, a insatisfa\u00e7\u00e3o difusa poderia ter sido diagnosticada, ao menos entre os universit\u00e1rios parisienses. No Brasil de hoje, a irrita\u00e7\u00e3o difusa podia ser claramente percebida na internet e nas redes sociais. O movimento pelo passe livre fez com que este mal-estar transbordasse do virtual para a realidade das ruas. Tanto os universit\u00e1rios franceses de 68, quanto os internautas do Brasil de hoje, n\u00e3o representam exatamente o que se poderia chamar de as massas ou o pov\u00e3o, mas funcionam igualmente como sensores e catalisadores de frustra\u00e7\u00f5es comuns.<\/p>\n<p>Quais as causas do mal-estar difuso no Brasil de hoje, que transbordou da internet para a realidade e levou a popula\u00e7\u00e3o \u00e0s ruas?<\/p>\n<p>Parecem ter dois eixos principais. O primeiro, e mais evidente, \u00e9 uma crise de representa\u00e7\u00e3o. A sociedade n\u00e3o se reconhece nos poderes constitu\u00eddos &#8211; Executivo, Legislativo e Judici\u00e1rio &#8211; em todas suas esferas. O segundo \u00e9 que o projeto do Estado brasileiro n\u00e3o corresponde mais aos anseios da popula\u00e7\u00e3o. O projeto do Estado, e n\u00e3o do governo, \u00e9 importante que se note, pois a quest\u00e3o transcende governos e oposi\u00e7\u00f5es. Este hiato entre o projeto do Estado e a sociedade explica em grande parte a crise de representa\u00e7\u00e3o.<\/p>\n<p>O Estado brasileiro mant\u00e9m-se preso a um projeto cuja formula\u00e7\u00e3o \u00e9 do in\u00edcio da segunda metade do s\u00e9culo passado. Um projeto que combina uma rede de prote\u00e7\u00e3o social com a industrializa\u00e7\u00e3o for\u00e7ada. A rede de prote\u00e7\u00e3o social inspirou-se nas reformas das economias capitalistas da Europa, entre as duas Grandes Guerras, refor\u00e7adas ap\u00f3s a crise dos anos 1930. Foi introduzida no Brasil por Get\u00falio Vargas, para a organiza\u00e7\u00e3o do mercado de trabalho, baseado no modelo da It\u00e1lia de Mussolini. A industrializa\u00e7\u00e3o for\u00e7ada atrav\u00e9s da substitui\u00e7\u00e3o de importa\u00e7\u00f5es, introduzida por Juscelino Kubitschek nos anos 1950, e refor\u00e7ada pelo regime militar nos anos 1970, tem ra\u00edzes mais aut\u00f3ctones. Suas origens intelectuais s\u00e3o o desenvolvimentismo latino-americano dos anos 1950, que defendia a a\u00e7\u00e3o direta do Estado, como empres\u00e1rio e planejador, para acelerar a industrializa\u00e7\u00e3o.<\/p>\n<p>N\u00e3o nos interessa aqui fazer a an\u00e1lise cr\u00edtica do projeto desenvolvimentista que, com altos e baixos, aos trancos e barrancos, cumpriu seu papel e levou o pa\u00eds \u00e0s portas da modernidade neste in\u00edcio de s\u00e9culo. Basta ressaltar que o desenvolvimentismo, em seus dois pilares &#8211; a industrializa\u00e7\u00e3o for\u00e7ada e a rede de prote\u00e7\u00e3o social &#8211; dependem da capacidade do Estado de extrair recursos da sociedade. Recursos que devem ser utilizados para financiar o investimento p\u00fablico e os benef\u00edcios da prote\u00e7\u00e3o social.<\/p>\n<p>Diante da baixa taxa de poupan\u00e7a do setor privado e da precariedade da estrutura tribut\u00e1ria do Estado, a infla\u00e7\u00e3o transferiu os recursos da sociedade para o Estado, at\u00e9 que nos anos 1980 viesse a se tornar completamente disfuncional. Com a infla\u00e7\u00e3o estabilizada, a partir do in\u00edcio dos anos 1990, o Estado se reorganizou para arrecadar por via fiscal tamb\u00e9m os recursos que extra\u00eda atrav\u00e9s do imposto inflacion\u00e1rio. A carga fiscal passou de menos de 15% da renda nacional, no in\u00edcio dos anos 1950, para em torno de 25%, nas d\u00e9cadas de 1970 a 90, at\u00e9 saltar para os atuais 36%, depois da estabiliza\u00e7\u00e3o da infla\u00e7\u00e3o. O Brasil tem hoje uma carga tribut\u00e1ria compar\u00e1vel, ou mesmo superior, \u00e0 das economias mais avan\u00e7adas.<\/p>\n<p>O projeto do PT no governo revelou-se flagrantemente retr\u00f3grado. \u00c9 essencialmente a volta do nacional- desenvolvimentismo<\/p>\n<p>Apesar de extrair da sociedade mais de um ter\u00e7o da renda nacional, o Estado perdeu a capacidade de realizar seu projeto. N\u00e3o o consegue entregar porque, apesar de arrecadar 36% da renda nacional, investe menos de 7% do que arrecada, ou seja, menos de 3% da renda nacional. Para onde v\u00e3o os outros 93% dos quase 40% da renda que extrai da sociedade? Parte, para a rede de prote\u00e7\u00e3o e assist\u00eancia social, que se expandiu muito al\u00e9m do mercado de trabalho organizado, mas, sobretudo, para sua pr\u00f3pria opera\u00e7\u00e3o. O Estado brasileiro tornou-se um sorvedouro de recursos, cujo principal objetivo \u00e9 financiar a si mesmo. Os sinais dessa situa\u00e7\u00e3o est\u00e3o t\u00e3o evidentes, que n\u00e3o \u00e9 preciso conhecer e analisar os n\u00fameros. O Executivo, com 39 minist\u00e9rios ausentes e inoperantes; o Legislativo, do qual s\u00f3 se tem m\u00e1s not\u00edcias e frustra\u00e7\u00f5es; o Judici\u00e1rio pomposo e exasperadoramente lento.<\/p>\n<p>O Estado foi tamb\u00e9m incapaz de perceber que seu projeto n\u00e3o corresponde mais ao que deseja a sociedade. O modelo desenvolvimentista do s\u00e9culo passado tinha dois pilares. Primeiro, a convic\u00e7\u00e3o de que a industrializa\u00e7\u00e3o era o \u00fanico caminho para escapar do subdesenvolvimento. Pa\u00edses de economia prim\u00e1rio-exportadora nunca poderiam almejar alcan\u00e7ar o est\u00e1gio de desenvolvimento das economias industrializadas. Segundo, a convic\u00e7\u00e3o de que o capitalismo moderno exige a interven\u00e7\u00e3o do Estado em tr\u00eas dimens\u00f5es: para estabilizar as crises c\u00edclicas das economias de mercado; para prover uma rede de prote\u00e7\u00e3o social; e, no caso dos pa\u00edses subdesenvolvidos, para liderar o processo de industrializa\u00e7\u00e3o acelerada. As duas primeiras dimens\u00f5es da a\u00e7\u00e3o do Estado s\u00e3o parte do consenso formado depois da crise dos anos 1930. A terceira decorre do sucesso do planejamento central sovi\u00e9tico em transformar uma economia agr\u00e1ria, semifeudal, numa pot\u00eancia industrial em poucas d\u00e9cadas. A prote\u00e7\u00e3o tarif\u00e1ria do mercado interno, com o objetivo de proteger a ind\u00fastria nascente e promover a substitui\u00e7\u00e3o de importa\u00e7\u00f5es, completava o card\u00e1pio com um toque de nacionalismo.<\/p>\n<p>O nacional- desenvolvimentismo, fermentado nos anos 1950, teve sua primeira formula\u00e7\u00e3o como plano de a\u00e7\u00e3o do governo na proposta de Roberto Simonsen. Embora sempre combatido pelos defensores mais radicais do liberalismo econ\u00f4mico, como Eug\u00eanio Gudin, autor de famosa pol\u00eamica com Roberto Simonsen, e posteriormente por Roberto Campos, foi adotado tanto pela esquerda, como pela direita. Seu per\u00edodo de maior sucesso foi justamente o do &#8220;milagre econ\u00f4mico&#8221; do regime militar.<\/p>\n<p>Na d\u00e9cada de 1980, a infla\u00e7\u00e3o se acelera e se torna definitivamente disfuncional. As sucessivas e fracassadas tentativas de estabiliza\u00e7\u00e3o passam a dominar o cen\u00e1rio econ\u00f4mico. Com a estabiliza\u00e7\u00e3o do real, a partir da segunda metade da d\u00e9cada de 1990, ainda com algum constrangimento em reconhecer que o nacional-desenvolvimentismo j\u00e1 n\u00e3o fazia sentido num mundo integrado pela globaliza\u00e7\u00e3o, o pa\u00eds parecia estar em busca de novos rumos. A vit\u00f3ria do PT foi, sem d\u00favida, parte da express\u00e3o desse anseio de mudan\u00e7a.<\/p>\n<p>Nos dois primeiros anos do governo Lula, a pol\u00edtica econ\u00f4mica foi essencialmente pautada pela necessidade de acalmar os mercados financeiros, sempre conservadores, assustados com a perspectiva de uma virada radical \u00e0 esquerda. A partir da\u00ed, o PT passou a p\u00f4r em pr\u00e1tica o seu projeto. Um projeto muito diferente do que defendia enquanto oposi\u00e7\u00e3o. O projeto do PT no governo, frustrando as expectativas dos que esperavam mudan\u00e7as, muito mais do que o aparente continu\u00edsmo dos primeiros anos do governo Lula, revelou-se flagrantemente retr\u00f3grado. \u00c9 essencialmente a volta do nacional-desenvolvimentismo, inspirado no per\u00edodo em este que foi mais bem-sucedido: durante regime militar. A crise internacional de 2008 serviu para que o governo abandonasse o temor de desagradar aos mercados financeiros e, sob pretexto de fazer pol\u00edtica macroecon\u00f4mica antic\u00edclica, promovesse definitivamente a volta do nacional-desenvolvimentismo estatal.<\/p>\n<p>O PT acrescentou dois elementos novos em rela\u00e7\u00e3o ao projeto nacional-desenvolvimentista do regime militar: a amplia\u00e7\u00e3o da rede de prote\u00e7\u00e3o social, com o Bolsa Fam\u00edlia, e o loteamento do Estado. A amplia\u00e7\u00e3o da rede de prote\u00e7\u00e3o social se justifica, tanto como uma inciativa capaz de romper o impasse da pobreza absoluta, em que, apesar dos avan\u00e7os da economia, grande parte da popula\u00e7\u00e3o brasileira se via aprisionada, quanto como forma de manter um m\u00ednimo de coer\u00eancia com seu discurso hist\u00f3rico. J\u00e1 a l\u00f3gica por tr\u00e1s do loteamento do Estado \u00e9 puramente pragm\u00e1tica. Ao contr\u00e1rio do regime militar, que n\u00e3o precisava de alian\u00e7as difusas, o PT utilizou o loteamento do Estado, em todas suas inst\u00e2ncias, como moeda de troca para compor uma ampla base de sustenta\u00e7\u00e3o. Sem nenhum pudor ideol\u00f3gico, juntou o sindicalismo de suas ra\u00edzes com o fisiologismo do que j\u00e1 foi chamado de Centr\u00e3o, atualmente representado principalmente pelo PMDB, no qual se encontra toda sorte de homens p\u00fablicos, que, independentemente de suas origens, perderam suas convic\u00e7\u00f5es ao longo da estrada e hoje s\u00e3o essencialmente c\u00ednicos.<\/p>\n<p>H\u00e1 ainda um terceiro elemento do projeto de poder do PT. Trata-se da elei\u00e7\u00e3o de uma parte do empresariado como aliada estrat\u00e9gica. Tais aliados t\u00eam acesso privilegiado ao cr\u00e9dito favorecido dos bancos p\u00fablicos e, sobretudo, \u00e0 boa vontade do governo, para crescerem, absorverem empresas em dificuldades, consolidarem suas posi\u00e7\u00f5es oligopol\u00edsticas no mercado interno e se aventurarem internacionalmente como &#8220;campe\u00f5es nacionais&#8221;.<\/p>\n<p>A combina\u00e7\u00e3o de um projeto anacr\u00f4nico com o loteamento do Estado entre o sindicalismo e o fisiologismo pol\u00edtico, ao contr\u00e1rio do pretendido, levou \u00e0 sobrevaloriza\u00e7\u00e3o cambial e \u00e0 desindustrializa\u00e7\u00e3o. S\u00f3 foi poss\u00edvel sustentar um crescimento econ\u00f4mico med\u00edocre enquanto durou a alta dos pre\u00e7os dos produtos prim\u00e1rios, puxados pela demanda da China. A inefici\u00eancia do Estado nas suas fun\u00e7\u00f5es b\u00e1sicas &#8211; seguran\u00e7a, infraestrutura, sa\u00fade e educa\u00e7\u00e3o &#8211; agravou-se significativamente. Inefici\u00eancia real\u00e7ada pela redu\u00e7\u00e3o da pobreza absoluta na popula\u00e7\u00e3o, que aumentou a demanda por servi\u00e7os de qualidade.<\/p>\n<p>A insatisfa\u00e7\u00e3o difusa dos protestos pode vir a ser catalizadora de uma mudan\u00e7a profunda de rumo, que abra o caminho para um novo desenvolvimento (na foto, manifestantes sobem ao teto do Congresso)<\/p>\n<p>Loteado e inadimplente em suas fun\u00e7\u00f5es essenciais, enquanto absorvia parcela cada vez maior da renda nacional para sua pr\u00f3pria opera\u00e7\u00e3o, o Estado passou a ser visto como um ileg\u00edtimo expropriador de recursos. N\u00e3o apenas incapaz de devolver \u00e0 sociedade o m\u00ednimo que dele se espera, mas tamb\u00e9m um criador de dificuldades. A combina\u00e7\u00e3o de uma excessiva regulamenta\u00e7\u00e3o de todas as esferas da vida, com a trucul\u00eancia e a arrog\u00e2ncia de seus agentes, consolidou o estranhamento da sociedade. Em todas as suas esferas, o Estado deixou de ser percebido como um aliado, representativo e prestador de servi\u00e7o. Passou a ser visto como um insaci\u00e1vel expropriador, cujo \u00fanico objetivo \u00e9 criar vantagens para os que dele fazem parte, enquanto imp\u00f5e dificuldades e cria obriga\u00e7\u00f5es para o resto da popula\u00e7\u00e3o. O contraste da realidade com o ufanismo da propaganda oficial s\u00f3 agravou o estranhamento e consolidou o div\u00f3rcio entre a popula\u00e7\u00e3o e os que deveriam ser seus representantes e servidores.<\/p>\n<p>A insatisfa\u00e7\u00e3o com a democracia representativa n\u00e3o \u00e9 um fen\u00f4meno exclusivamente brasileiro. As raz\u00f5es dessa insatisfa\u00e7\u00e3o ainda n\u00e3o est\u00e3o claras, mas \u00e9 poss\u00edvel que o modelo de representa\u00e7\u00e3o democr\u00e1tica, constitu\u00eddo h\u00e1 dois s\u00e9culos para sociedades menores e mais homog\u00eaneas, tenha deixado de cumprir seu papel num mundo interligado de 7 bilh\u00f5es de pessoas, e precise ser revisto. O debate p\u00fablico deslocou-se das esferas tradicionais da pol\u00edtica para a internet e as redes sociais. Amea\u00e7ada pelo crescimento da internet e habituada ao seu papel de agente da pol\u00edtica tradicional, a m\u00eddia n\u00e3o percebeu que o debate havia se deslocado.<\/p>\n<p>No caso brasileiro, perplexa com sua aparente falta de repercuss\u00e3o e pressionada financeiramente pela competi\u00e7\u00e3o da internet, uma parte da m\u00eddia desistiu do jornalismo de interesse p\u00fablico e passou a fazer um jornalismo de puro entretenimento. Mesmo os que resistiram, cederam, em maior ou menor escala, \u00e0 l\u00f3gica dos esc\u00e2ndalos. Foram incapazes de compreender a raz\u00e3o da sua falta de repercuss\u00e3o, pois n\u00e3o se deram conta de que o p\u00fablico e o debate haviam se deslocado para a internet. Surpreendida pelo movimento de protestos, num primeiro momento, a m\u00eddia n\u00e3o foi capaz de avaliar a extens\u00e3o da insatisfa\u00e7\u00e3o. Transformou-se ela pr\u00f3pria em alvo da irrita\u00e7\u00e3o popular. Em seguida, aderiu sem convencer, sempre a reboque do debate e da mobiliza\u00e7\u00e3o atrav\u00e9s da internet. A favor da m\u00eddia, diga-se que ningu\u00e9m foi capaz de captar a insatisfa\u00e7\u00e3o latente antes da eclos\u00e3o do movimento das ruas. As pesquisas apontavam, at\u00e9 muito recentemente, grande apoio \u00e0 presidente da Rep\u00fablica, considerada praticamente imbat\u00edvel, at\u00e9 mesmo por seus eventuais advers\u00e1rios nas pr\u00f3ximas elei\u00e7\u00f5es. Nenhuma lideran\u00e7a soube captar e expressar o mal-estar contempor\u00e2neo. Este \u00e9 provavelmente o seu elemento novo: a internet viabiliza a mobiliza\u00e7\u00e3o antes que surjam as lideran\u00e7as. Tanto as possibilidades como os riscos s\u00e3o novos.<\/p>\n<p>O projeto nacional-desenvolvimentista combina o consumismo das economias capitalistas avan\u00e7adas com o produtivismo sovi\u00e9tico. Ambos pressup\u00f5em que o crescimento material \u00e9 o objetivo final da atividade humana. A\u00ed est\u00e1 a ess\u00eancia de seu car\u00e1ter anacr\u00f4nico. Os avan\u00e7os da inform\u00e1tica permitiram a coleta de um volume extraordin\u00e1rio de evid\u00eancias sobre a psicologia e os componentes do bem-estar. A rela\u00e7\u00e3o entre renda e bem-estar s\u00f3 \u00e9 claramente positiva at\u00e9 um n\u00edvel relativamente baixo de renda, capaz de atender \u00e0s necessidades b\u00e1sicas da vida. A partir da\u00ed, o aumento do bem-estar est\u00e1 associado ao que se pode chamar de qualidade de vida, cujos elementos fundamentais s\u00e3o o tempo com a fam\u00edlia e os amigos, o sentido de comunidade e confian\u00e7a nos concidad\u00e3os, a sa\u00fade e a aus\u00eancia de estresse emocional.<\/p>\n<p>Os estudos da moderna psicologia comprovam aquilo que de uma forma ou de outra, mais ou menos conscientemente, intu\u00edmos todos: nossa insaciabilidade de bens materiais adv\u00e9m do fato de que o bem-estar que nos trazem \u00e9 ef\u00eamero. Para manter a sensa\u00e7\u00e3o de bem-estar, precisamos de mais e novas aquisi\u00e7\u00f5es. O consumismo material tem elementos parecidos com o do uso de subst\u00e2ncias entorpecentes que causam depend\u00eancia f\u00edsica e psicol\u00f3gica.<\/p>\n<p>No mundo todo, a popula\u00e7\u00e3o parece j\u00e1 ter intu\u00eddo a exaust\u00e3o do modelo consumista do s\u00e9culo XX, mas ainda n\u00e3o encontrou nas esferas da pol\u00edtica tradicional a capacidade de participar da formula\u00e7\u00e3o das alternativas. Apegada a f\u00f3rmulas feitas, a pol\u00edtica continua pautada pelos temas e objetivos de um mundo que n\u00e3o corresponde mais \u00e0 realidade de hoje. As grandes propostas totalizantes j\u00e1 n\u00e3o fazem sentido. O nacionalismo, a obsess\u00e3o com o crescimento material, a \u00eanfase no consumo sup\u00e9rfluo, os grandes embates ideol\u00f3gicos, temas que dominaram a pol\u00edtica nos \u00faltimos dois s\u00e9culos, perderam import\u00e2ncia. Hoje, o que importa s\u00e3o quest\u00f5es concretas, relativas ao cotidiano, quest\u00f5es de efici\u00eancia administrativa para garantir a qualidade de vida.<\/p>\n<p>\u00c9 significativo que os protestos no Brasil tenham come\u00e7ado com a reivindica\u00e7\u00e3o do passe livre nos transportes p\u00fablicos urbanos. A quest\u00e3o da mobilidade nas grandes metr\u00f3poles \u00e9 paradigm\u00e1tica da exaust\u00e3o do modelo produtivista-consumista. A ind\u00fastria automobil\u00edstica foi o pilar da industrializa\u00e7\u00e3o desenvolvimentista e o autom\u00f3vel o s\u00edmbolo supremo da aspira\u00e7\u00e3o consumista. O inferno do tr\u00e2nsito nas grandes cidades, que se agrava quanto mais bem-sucedido \u00e9 o projeto desenvolvimentista, \u00e9 a express\u00e3o m\u00e1xima da completa inviabilidade de prosseguir sem uma revis\u00e3o profunda de objetivos. Ao que parece, a sociedade intuiu a fal\u00eancia do projeto do s\u00e9culo passado antes que o Estado e aqueles que deveriam represent\u00e1-la &#8211; governo e oposi\u00e7\u00e3o, Executivo, Legislativo e imprensa &#8211; tenham se dado conta de que hoje trabalham com objetivos anacr\u00f4nicos.<\/p>\n<p>A insatisfa\u00e7\u00e3o difusa dos protestos pode vir a ser catalizadora de uma mudan\u00e7a profunda de rumo, que abra o caminho para um novo desenvolvimento, n\u00e3o mais baseado exclusivamente no crescimento do consumo material, mas na qualidade de vida. Para isso, \u00e9 preciso que surjam lideran\u00e7as capazes de exprimir, formular e executar o novo desenvolvimento.<\/p>\n<p><strong>Andr\u00e9 Lara Resende \u00e9 economista. Este texto ser\u00e1 apresentado na Festa Liter\u00e1ria de Paraty (Flip), em debate com o fil\u00f3sofo Marcos Nobre, que ocorre neste s\u00e1bado.<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>De tudo que li nestas semanas sobre o sentido das manifesta\u00e7\u00f5es de rua no Brasil, este texto de Andr\u00e9 Lara Resende, Publicado no Valor Econ\u00f4mico de 5 de julho, \u00e9 provavelmente o que melhor interpreta o que vem ocorrendo, e por isto precisa ser lido com muita aten\u00e7\u00e3o e compartido. Estou fazendo minha parte. O &hellip; <a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/andre-lara-resende-o-mal-estar-contemporeano\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Andr\u00e9 Lara Resende: O Mal-Estar Contempor\u00eaano&#8221;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[19],"tags":[],"class_list":["post-4540","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/4540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/comments?post=4540"}],"version-history":[{"count":2,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/4540\/revisions"}],"predecessor-version":[{"id":4542,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/4540\/revisions\/4542"}],"wp:attachment":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/media?parent=4540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/categories?post=4540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/tags?post=4540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}