{"id":4796,"date":"2014-02-24T19:38:38","date_gmt":"2014-02-24T22:38:38","guid":{"rendered":"http:\/\/www.schwartzman.org.br\/sitesimon\/?p=4796"},"modified":"2014-02-24T19:38:38","modified_gmt":"2014-02-24T22:38:38","slug":"pronunciamento-das-academias-de-ciencia-da-venezuela-contra-a-violencia-e-pelo-pluralismo","status":"publish","type":"post","link":"https:\/\/www.schwartzman.org.br\/sitesimon\/pronunciamento-das-academias-de-ciencia-da-venezuela-contra-a-violencia-e-pelo-pluralismo\/","title":{"rendered":"Pronunciamento das Academias de Ci\u00eancia da Venezuela: contra a viol\u00eancia e pelo pluralismo"},"content":{"rendered":"<p><script type='application\/json' class='__iawmlf-post-loop-links'>[{\"id\":458,\"href\":\"http:\\\/\\\/www.schwartzman.org.br\\\/comiteineracademici.pdf\",\"archived_href\":\"https:\\\/\\\/web-wp.archive.org\\\/web\\\/20250617121634\\\/http:\\\/\\\/www.schwartzman.org.br\\\/comiteineracademici.pdf\",\"redirect_href\":\"\",\"checks\":[{\"date\":\"2026-04-19 13:25:02\",\"http_code\":206},{\"date\":\"2026-04-25 10:21:58\",\"http_code\":206},{\"date\":\"2026-04-28 15:44:03\",\"http_code\":206},{\"date\":\"2026-05-03 09:18:16\",\"http_code\":206},{\"date\":\"2026-05-09 01:53:21\",\"http_code\":503}],\"broken\":false,\"last_checked\":{\"date\":\"2026-05-09 01:53:21\",\"http_code\":503},\"process\":\"done\"}]<\/script>Diante da viol\u00eancia do governo contra a manifesta\u00e7\u00f5es p\u00fablicas de protesto, as academias de ci\u00eancia da Venezuela lan\u00e7aram um documento em que, al\u00e9m de exigir do governo que acabe com a repress\u00e3o e garanta os direitos democr\u00e1ticos de express\u00e3o, recha\u00e7a de maneira categ\u00f3rica &#8220;todo o intento de impor um pensamento \u00fanico na condu\u00e7\u00e3o do pa\u00eds&#8221;. O documento do Comit\u00ea Interacad\u00eamico das Academias Nacionais <a href=\"http:\/\/www.schwartzman.org.br\/comiteineracademici.pdf\" target=\"_blank\">est\u00e1 dispon\u00edvel aqui.<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Diante da viol\u00eancia do governo contra a manifesta\u00e7\u00f5es p\u00fablicas de protesto, as academias de ci\u00eancia da Venezuela lan\u00e7aram um documento em que, al\u00e9m de exigir do governo que acabe com a repress\u00e3o e garanta os direitos democr\u00e1ticos de express\u00e3o, recha\u00e7a de maneira categ\u00f3rica &#8220;todo o intento de impor um pensamento \u00fanico na condu\u00e7\u00e3o do pa\u00eds&#8221;. &hellip; <a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/pronunciamento-das-academias-de-ciencia-da-venezuela-contra-a-violencia-e-pelo-pluralismo\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Pronunciamento das Academias de Ci\u00eancia da Venezuela: contra a viol\u00eancia e pelo pluralismo&#8221;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-4796","post","type-post","status-publish","format-standard","hentry","category-politica-internacional"],"_links":{"self":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/4796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/comments?post=4796"}],"version-history":[{"count":1,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/4796\/revisions"}],"predecessor-version":[{"id":4797,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/4796\/revisions\/4797"}],"wp:attachment":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/media?parent=4796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/categories?post=4796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/tags?post=4796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}