{"id":4808,"date":"2014-04-01T08:11:22","date_gmt":"2014-04-01T11:11:22","guid":{"rendered":"http:\/\/www.schwartzman.org.br\/sitesimon\/?p=4808"},"modified":"2014-04-01T08:11:22","modified_gmt":"2014-04-01T11:11:22","slug":"capacidade-de-resolver-problemas-como-anda-o-brasil","status":"publish","type":"post","link":"https:\/\/www.schwartzman.org.br\/sitesimon\/capacidade-de-resolver-problemas-como-anda-o-brasil\/","title":{"rendered":"Capacidade de resolver problemas: como anda o Brasil?"},"content":{"rendered":"<p><script type='application\/json' class='__iawmlf-post-loop-links'>[{\"id\":456,\"href\":\"http:\\\/\\\/www.oecd.org\\\/pisa\\\/keyfindings\\\/PISA-2012-results-volume-V.pdf\",\"archived_href\":\"\",\"redirect_href\":\"\",\"checks\":[],\"broken\":false,\"last_checked\":null,\"process\":\"done\"}]<\/script><a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-content\/uploads\/2014\/04\/performers.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-4811\" alt=\"performers\" src=\"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-content\/uploads\/2014\/04\/performers.jpg\" width=\"407\" height=\"338\" srcset=\"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-content\/uploads\/2014\/04\/performers.jpg 754w, https:\/\/www.schwartzman.org.br\/sitesimon\/wp-content\/uploads\/2014\/04\/performers-300x249.jpg 300w\" sizes=\"auto, (max-width: 407px) 85vw, 407px\" \/><\/a><\/p>\n<p>A OECD acaba de publicar os resultados da avalia\u00e7\u00e3o feita em 2012 sobre a capacidade dos estudantes de 15 anos de resolver problemas pr\u00e1ticos da vida real, parte do programa internacional de avalia\u00e7\u00e3o da educa\u00e7\u00e3o (PISA), cujo <a href=\"http:\/\/www.oecd.org\/pisa\/keyfindings\/PISA-2012-results-volume-V.pdf\" target=\"_blank\">texto completo est\u00e1 dispon\u00edvel aqui.<\/a>\u00a0 A amostra \u00e9 de estudantes que est\u00e3o cursando as s\u00e9ries correspondentes \u00e0 sua idade (no final do ensino fundamental ou in\u00edcio do m\u00e9dio). Os estudantes que se saem melhor s\u00e3o os da \u00c1sia (Singapura, Cor\u00e9ia, e diversas prov\u00edncias da China), seguidos pelo Canad\u00e1 e pa\u00edses europeus. Estes resultados derrubam o mito de que os estudantes na \u00c1sia s\u00e3o mais aplicados, mas os europeus e americanos seriam mais criativos e inventivos. \u00a0Na realidade, altos n\u00edveis de educa\u00e7\u00e3o, conhecimento e capacidade de resolve problemas pr\u00e1ticos s\u00e3o insepar\u00e1veis.<\/p>\n<p>Os resultados do Brasil, para variar, s\u00e3o muito ruins. Dos 44 pa\u00edses e regi\u00f5es que participaram do estudo, o Brasil est\u00e1 na posi\u00e7\u00e3o 38, melhor do que Uruguai e Col\u00f4mbia na Am\u00e9rica Latina, mas bem abaixo do Chile (os Estados Unidos est\u00e3o na posi\u00e7\u00e3o 18).<\/p>\n<p>O gr\u00e1fico ao lado compara a distribui\u00e7\u00e3o dos resultados do Brasil com os da Espanha, Chile, Portugal e Canad\u00e1, em 6 n\u00edveis de desempenho. Nesta classifica\u00e7\u00e3o, os de n\u00edvel \u00a0V e VI s\u00e3o os &#8220;top performers&#8221;, \u00a0os de n\u00edvel IV s\u00e3o &#8220;strong performers&#8221;, os de n\u00edvel II e III s\u00e3o &#8220;moderaste performance&#8221;, e os de I ou menos s\u00e3o &#8220;poor performers&#8221;. \u00a0Nesta escala, 47% dois estudantes brasileiros aos 15 anos s\u00e3o &#8220;poor performers&#8221;, e somente 1.8 est\u00e3o na categoria &#8220;top&#8221;. Em contraste, no Canad\u00e1, 17.5% est\u00e3o na categoria &#8220;top&#8221;. \u00a0Na Cor\u00e9ia, esta percentagem sobe para 27.6%, e s\u00f3 6.9% dos estudantes est\u00e3o na categoria &#8220;poor&#8221;.<\/p>\n<p>Na Am\u00e9rica Latina, o \u00fanico pa\u00eds que mostra resultados mais significativos \u00e9 o Chile, com menos estudantes nas categorias mais baixas do que o Brasil, mas ainda sem conseguir formar muitos estudantes de alto desempenho. \u00a0Portugal e Espanha est\u00e3o bem abaixo de outros pa\u00edses europeus, mas ainda bem melhores do que Brasil e Chile.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>A OECD acaba de publicar os resultados da avalia\u00e7\u00e3o feita em 2012 sobre a capacidade dos estudantes de 15 anos de resolver problemas pr\u00e1ticos da vida real, parte do programa internacional de avalia\u00e7\u00e3o da educa\u00e7\u00e3o (PISA), cujo texto completo est\u00e1 dispon\u00edvel aqui.\u00a0 A amostra \u00e9 de estudantes que est\u00e3o cursando as s\u00e9ries correspondentes \u00e0 sua &hellip; <a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/capacidade-de-resolver-problemas-como-anda-o-brasil\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Capacidade de resolver problemas: como anda o Brasil?&#8221;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[22],"tags":[],"class_list":["post-4808","post","type-post","status-publish","format-standard","hentry","category-educacao"],"_links":{"self":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/4808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/comments?post=4808"}],"version-history":[{"count":1,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/4808\/revisions"}],"predecessor-version":[{"id":4812,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/4808\/revisions\/4812"}],"wp:attachment":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/media?parent=4808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/categories?post=4808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/tags?post=4808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}