{"id":5863,"date":"2018-02-28T23:03:29","date_gmt":"2018-03-01T02:03:29","guid":{"rendered":"http:\/\/www.schwartzman.org.br\/sitesimon\/?p=5863"},"modified":"2025-02-20T04:45:44","modified_gmt":"2025-02-20T07:45:44","slug":"a-contribuicao-da-educacao-para-o-progresso-social","status":"publish","type":"post","link":"https:\/\/www.schwartzman.org.br\/sitesimon\/a-contribuicao-da-educacao-para-o-progresso-social\/","title":{"rendered":"A contribui\u00e7\u00e3o da educa\u00e7\u00e3o para o progresso social"},"content":{"rendered":"<p><script type='application\/json' class='__iawmlf-post-loop-links'>[{\"id\":222,\"href\":\"https:\\\/\\\/www.cambridge.org\\\/core\\\/books\\\/rethinking-society-for-the-21st-century\\\/046E7282B2B3DC56C16A3C02E4082D1B\",\"archived_href\":\"https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260415170155\\\/https:\\\/\\\/www.cambridge.org\\\/core\\\/books\\\/rethinking-society-for-the-21st-century\\\/046E7282B2B3DC56C16A3C02E4082D1B\",\"redirect_href\":\"\",\"checks\":[{\"date\":\"2026-04-19 17:13:40\",\"http_code\":200},{\"date\":\"2026-04-24 14:52:06\",\"http_code\":200},{\"date\":\"2026-04-28 06:56:49\",\"http_code\":200},{\"date\":\"2026-05-02 06:26:37\",\"http_code\":200},{\"date\":\"2026-05-11 08:38:57\",\"http_code\":200}],\"broken\":false,\"last_checked\":{\"date\":\"2026-05-11 08:38:57\",\"http_code\":200},\"process\":\"done\"}]<\/script><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5864 \" src=\"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-content\/uploads\/2018\/02\/ipsp-744x540.jpeg\" alt=\"\" width=\"626\" height=\"454\" srcset=\"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-content\/uploads\/2018\/02\/ipsp-744x540.jpeg 744w, https:\/\/www.schwartzman.org.br\/sitesimon\/wp-content\/uploads\/2018\/02\/ipsp-420x305.jpeg 420w, https:\/\/www.schwartzman.org.br\/sitesimon\/wp-content\/uploads\/2018\/02\/ipsp-768x558.jpeg 768w, https:\/\/www.schwartzman.org.br\/sitesimon\/wp-content\/uploads\/2018\/02\/ipsp.jpeg 825w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/p>\n<p>O International Panel for Social Progress\u00a0\u00a0\u00e9 uma iniciativa de tem reunido, desde 2015, centenas de cientistas sociais de todo o mundo em um esfor\u00e7o para pensar em que medida a pesquisa social pode dar respostas aos grandes desafios do s\u00e9culo 21. O primeiro resultado deste trabalho est\u00e1 por ser publicado proximamente pela Cambridge University Press, em 3 volumes e 22 cap\u00edtulos sob o t\u00edtulo de <a href=\"https:\/\/www.cambridge.org\/core\/books\/rethinking-society-for-the-21st-century\/046E7282B2B3DC56C16A3C02E4082D1B\">Rethinking Society for the 21st Century\u00a0<\/a>e as vers\u00f5es preliminares dos textos est\u00e3o dispon\u00edveis na Internet.<\/p>\n<p>\u00c9 com prazer que comparto a vers\u00e3o brasileira do cap\u00edtulo 19, sobre A<strong>\u00a0Contribui\u00e7\u00e3o da Educa\u00e7\u00e3o para o Progresso Socia<\/strong>l, publicada pela revista Ci\u00eancia &amp; Tr\u00f3pico, e dispon\u00edvel na Internet. \u00a0O texto, que ajudei a coordenar, foi preparado por um grupo com participantes da \u00c1frica do Sul, Alemanha, \u00a0Austria, Brasil, \u00cdndia, Israel, e Reino Unido, e pretende identificar, primeiro, quais s\u00e3o as grandes fun\u00e7\u00f5es que as sociedades esperam que a educa\u00e7\u00e3o desempenhe &#8211; o desenvolvimento human\u00edstico, a equidade \u00a0a coes\u00e3o social \u00a0e o desenvolvimento econ\u00f4mico &#8211; e, o que as pesquisas sociais nos dizem sobre como a educa\u00e7\u00e3o de fato tem contribuido ou pode contribuir para estes fins. Foi um esfor\u00e7o de colocar uma grande quantidade de ideias e informa\u00e7\u00f5es em um texto relativamente pequeno, por um grupo constituido por pessoas de diferentes \u00a0forma\u00e7\u00f5es e maneiras de ver o mundo. Cabe aos leitores dizer se conseguimos ou n\u00e3o cumprir bem a tarefa.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>O International Panel for Social Progress\u00a0\u00a0\u00e9 uma iniciativa de tem reunido, desde 2015, centenas de cientistas sociais de todo o mundo em um esfor\u00e7o para pensar em que medida a pesquisa social pode dar respostas aos grandes desafios do s\u00e9culo 21. O primeiro resultado deste trabalho est\u00e1 por ser publicado proximamente pela Cambridge University Press, &hellip; <a href=\"https:\/\/www.schwartzman.org.br\/sitesimon\/a-contribuicao-da-educacao-para-o-progresso-social\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;A contribui\u00e7\u00e3o da educa\u00e7\u00e3o para o progresso social&#8221;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[22],"tags":[],"class_list":["post-5863","post","type-post","status-publish","format-standard","hentry","category-educacao"],"_links":{"self":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/5863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/comments?post=5863"}],"version-history":[{"count":5,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/5863\/revisions"}],"predecessor-version":[{"id":7558,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/posts\/5863\/revisions\/7558"}],"wp:attachment":[{"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/media?parent=5863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/categories?post=5863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwartzman.org.br\/sitesimon\/wp-json\/wp\/v2\/tags?post=5863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}